{"id":1738,"date":"2015-07-23T16:55:43","date_gmt":"2015-07-23T21:55:43","guid":{"rendered":"https:\/\/accesolatino.org\/?p=1738"},"modified":"2025-10-29T21:57:02","modified_gmt":"2025-10-30T03:57:02","slug":"inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/","title":{"rendered":"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os"},"content":{"rendered":"<p><strong>Seg\u00fan estad\u00edsticas de la Patrulla Fronteriza de los Estados Unidos la inmigraci\u00f3n indocumentada en la frontera con M\u00e9xico ha tenido un crecimiento del 456 por ciento en el periodo que comprende de 1925 a 2014.<\/strong><\/p>\n<p>Hay dos a\u00f1os en los que la inmigraci\u00f3n indocumentada fue especialmente alta; estos a\u00f1os son: 1986 (1 mill\u00f3n 692 mil 544 arrestos) y 1990 (1 mill\u00f3n 579 mil 10 arrestos).<\/p>\n<p>Los arrestos de personas indocumentadas se dieron principalmente en los puertos frotnerizos terrestres de Valle del R\u00edo Grande, Laredo, El Paso, San Diego y Tucson.<\/p>\n<p><strong>La Patrulla Fronteriza detalla que a partir del A\u00f1o Fiscal de 2007 el fen\u00f3meno de personas indocumentadas que cruzan la frontera sufri\u00f3 una desaceleraci\u00f3n ya que en 2007 fueron capturados 876 mil 704 indocumentados y en 2014 solo fueron apresados 486 mil 651 indocumentados.<\/strong><\/p>\n<p>La mayor\u00eda de las personas indocumentadas detenidas son originarios de Guatemala, Honduras, El Salvador y M\u00e9xico.<\/p>\n<p>Los expertos creen que el refuerzo en la vigilancia por parte de la Patrulla Fronteriza ha impedido que miles de indocumentados ingresen o permanezcan en territorio de los Estados Unidos.<\/p>\n<p>Alejandro Aguilera un inmigrante indocumentado explica lo dif\u00edcil que puede ser cruzar la frontera: <em>\u201cmuchas tecnolog\u00edas, tecnol\u00f3gicamente pues tienen mucha, mucha vigilancia, y hay cosas como los sensores, muchas cosas as\u00ed (sic)\u201d.<\/em><\/p>\n<p>Adem\u00e1s la Patrulla Fronteriza ha implementado diversas campa\u00f1as internacionales sobre los peligros de cruzar de forma ilegal a la Uni\u00f3n Americana.<\/p>\n<p>Enrique Mart\u00ednez, Asistente de Jefe de la Patrulla Fronteriza del Sector Laredo explic\u00f3 que su organizaci\u00f3n trata de dejar en claro y dar informaci\u00f3n sobre los problemas que puede causar cruzar la frontera.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuente:<\/strong> <em>Revista Sin Frontera<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan estad\u00edsticas de la Patrulla Fronteriza de los Estados Unidos la inmigraci\u00f3n indocumentada en la frontera con M\u00e9xico ha tenido un crecimiento del 456 por ciento en el periodo que comprende de 1925 a 2014. Hay dos a\u00f1os en los que la inmigraci\u00f3n indocumentada fue especialmente alta; estos a\u00f1os son: 1986 (1 mill\u00f3n 692 mil 544 arrestos) y 1990 (1 mill\u00f3n 579 mil 10 arrestos). Los arrestos de personas indocumentadas se dieron principalmente en los puertos frotnerizos terrestres de Valle del R\u00edo Grande, Laredo, El Paso, San Diego y Tucson. La Patrulla Fronteriza detalla que a partir del A\u00f1o Fiscal de 2007 el fen\u00f3meno de personas indocumentadas que cruzan la frontera sufri\u00f3 una desaceleraci\u00f3n ya que en 2007 fueron capturados 876 mil 704 indocumentados y en 2014 solo fueron apresados 486 mil 651 indocumentados. La mayor\u00eda de las personas indocumentadas detenidas son originarios de Guatemala, Honduras, El Salvador y M\u00e9xico. Los expertos creen que el refuerzo en la vigilancia por parte de la Patrulla Fronteriza ha impedido que miles de indocumentados ingresen o permanezcan en territorio de los Estados Unidos. Alejandro Aguilera un inmigrante indocumentado explica lo dif\u00edcil que puede ser cruzar la frontera: \u201cmuchas tecnolog\u00edas, tecnol\u00f3gicamente pues tienen mucha, mucha vigilancia, y hay cosas como los sensores, muchas cosas as\u00ed (sic)\u201d. Adem\u00e1s la Patrulla Fronteriza ha implementado diversas campa\u00f1as internacionales sobre los peligros de cruzar de forma ilegal a la Uni\u00f3n Americana. Enrique Mart\u00ednez, Asistente de Jefe de la Patrulla Fronteriza del Sector Laredo explic\u00f3 que su organizaci\u00f3n trata de dejar en claro y dar informaci\u00f3n sobre los problemas que puede causar cruzar la frontera. &nbsp; Fuente: Revista Sin Frontera<\/p>","protected":false},"author":13,"featured_media":1739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-1738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os<\/title>\n<meta name=\"description\" content=\"La inmigraci\u00f3n indocumentada en la frontera con M\u00e9xico ha tenido un crecimiento del 456 por ciento en el periodo que comprende de 1925 a 2014.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os\" \/>\n<meta property=\"og:description\" content=\"La inmigraci\u00f3n indocumentada en la frontera con M\u00e9xico ha tenido un crecimiento del 456 por ciento en el periodo que comprende de 1925 a 2014.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-23T21:55:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T03:57:02+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os\",\"datePublished\":\"2015-07-23T21:55:43+00:00\",\"dateModified\":\"2025-10-30T03:57:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/\"},\"wordCount\":286,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/\",\"name\":\"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-07-23T21:55:43+00:00\",\"dateModified\":\"2025-10-30T03:57:02+00:00\",\"description\":\"La inmigraci\u00f3n indocumentada en la frontera con M\u00e9xico ha tenido un crecimiento del 456 por ciento en el periodo que comprende de 1925 a 2014.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os","description":"La inmigraci\u00f3n indocumentada en la frontera con M\u00e9xico ha tenido un crecimiento del 456 por ciento en el periodo que comprende de 1925 a 2014.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os","og_description":"La inmigraci\u00f3n indocumentada en la frontera con M\u00e9xico ha tenido un crecimiento del 456 por ciento en el periodo que comprende de 1925 a 2014.","og_url":"https:\/\/accesolatino.org\/en\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-07-23T21:55:43+00:00","article_modified_time":"2025-10-30T03:57:02+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os","datePublished":"2015-07-23T21:55:43+00:00","dateModified":"2025-10-30T03:57:02+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/"},"wordCount":286,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/","name":"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-07-23T21:55:43+00:00","dateModified":"2025-10-30T03:57:02+00:00","description":"La inmigraci\u00f3n indocumentada en la frontera con M\u00e9xico ha tenido un crecimiento del 456 por ciento en el periodo que comprende de 1925 a 2014.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/inmigracion-indocumentada-crecio-456-por-ciento-en-80-anos\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Inmigraci\u00f3n indocumentada creci\u00f3 456 por ciento en 80 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/1738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=1738"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/1738\/revisions"}],"predecessor-version":[{"id":68178,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/1738\/revisions\/68178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=1738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=1738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=1738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}