{"id":1706,"date":"2015-07-20T11:55:33","date_gmt":"2015-07-20T16:55:33","guid":{"rendered":"https:\/\/accesolatino.org\/?p=1706"},"modified":"2025-10-29T22:39:05","modified_gmt":"2025-10-30T04:39:05","slug":"dmv-ha-otorgado-400-mil-licencias-a-indocumentados","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/","title":{"rendered":"DMV ha otorgado 400 mil licencias a indocumentados"},"content":{"rendered":"<p><strong>El Departamento de Veh\u00edculos Motorizados de California<\/strong> (DMV, por sus siglas en ingl\u00e9s)<strong> anunci\u00f3 que durante los primeros seis meses de este a\u00f1o los inmigrantes indocumentados obtuvieron casi 400 mil licencias de conducir.<\/strong><\/p>\n<p>En el reporte dado a conocer el viernes, el DMV revela que de las 759 mil licencias de conducir otorgadas de enero a junio de este a\u00f1o, 397 mil fueron otorgadas a inmigrantes sin un estatus migratorio.<\/p>\n<p>Jean Shiomoto, directora del DMV de California explic\u00f3 que estos n\u00famero reflejan &#8220;<em>el \u00e9xito en la implementaci\u00f3n de la ley AB 60<\/em>&#8221; (esta ley otorga licencias de conducir a las personas sin un estatus migratorio.<\/p>\n<p><strong>El gobernador del estado, Jerry Brown, firm\u00f3 la la ley en 2013 para otorgar licencias a los indocumentados para poder manejar sin miedo a la deportaci\u00f3n.<\/strong> Los activistas por los derechos de los inmigrantes argumentan que esta ley hace m\u00e1s seguros los caminos ya obliga a los inmigrantes indocumentados a pasar un examen de conducir y adquirir un seguro para su veh\u00edculo.<\/p>\n<p>Jackelin Aguilar, organizadora comunitaria de Placer People of Faith Together mencion\u00f3 que este es &#8220;un gran paso para que los inmigrantes indocumentados tengan una identificaci\u00f3n&#8221;.<\/p>\n<p><strong>Adem\u00e1s de California hay otros 9 estados que se suman al Distrito de Columbia y Puerto Rico que otorgan licencias de conducir a los inmigrantes indocumentados.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuente:<\/strong><em> Latin Post<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>El Departamento de Veh\u00edculos Motorizados de California (DMV, por sus siglas en ingl\u00e9s) anunci\u00f3 que durante los primeros seis meses de este a\u00f1o los inmigrantes indocumentados obtuvieron casi 400 mil licencias de conducir. En el reporte dado a conocer el viernes, el DMV revela que de las 759 mil licencias de conducir otorgadas de enero a junio de este a\u00f1o, 397 mil fueron otorgadas a inmigrantes sin un estatus migratorio. Jean Shiomoto, directora del DMV de California explic\u00f3 que estos n\u00famero reflejan &#8220;el \u00e9xito en la implementaci\u00f3n de la ley AB 60&#8221; (esta ley otorga licencias de conducir a las personas sin un estatus migratorio. El gobernador del estado, Jerry Brown, firm\u00f3 la la ley en 2013 para otorgar licencias a los indocumentados para poder manejar sin miedo a la deportaci\u00f3n. Los activistas por los derechos de los inmigrantes argumentan que esta ley hace m\u00e1s seguros los caminos ya obliga a los inmigrantes indocumentados a pasar un examen de conducir y adquirir un seguro para su veh\u00edculo. Jackelin Aguilar, organizadora comunitaria de Placer People of Faith Together mencion\u00f3 que este es &#8220;un gran paso para que los inmigrantes indocumentados tengan una identificaci\u00f3n&#8221;. Adem\u00e1s de California hay otros 9 estados que se suman al Distrito de Columbia y Puerto Rico que otorgan licencias de conducir a los inmigrantes indocumentados. &nbsp; Fuente: Latin Post<\/p>","protected":false},"author":13,"featured_media":1707,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-1706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DMV ha otorgado 400 mil licencias a indocumentados<\/title>\n<meta name=\"description\" content=\"El DMV de California anunci\u00f3 que durante los primeros seis meses de este a\u00f1o los inmigrantes indocumentados obtuvieron casi 400 mil licencias de conducir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DMV ha otorgado 400 mil licencias a indocumentados\" \/>\n<meta property=\"og:description\" content=\"El DMV de California anunci\u00f3 que durante los primeros seis meses de este a\u00f1o los inmigrantes indocumentados obtuvieron casi 400 mil licencias de conducir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-20T16:55:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T04:39:05+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"DMV ha otorgado 400 mil licencias a indocumentados\",\"datePublished\":\"2015-07-20T16:55:33+00:00\",\"dateModified\":\"2025-10-30T04:39:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/\"},\"wordCount\":234,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/\",\"name\":\"DMV ha otorgado 400 mil licencias a indocumentados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-07-20T16:55:33+00:00\",\"dateModified\":\"2025-10-30T04:39:05+00:00\",\"description\":\"El DMV de California anunci\u00f3 que durante los primeros seis meses de este a\u00f1o los inmigrantes indocumentados obtuvieron casi 400 mil licencias de conducir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DMV ha otorgado 400 mil licencias a indocumentados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DMV ha otorgado 400 mil licencias a indocumentados","description":"El DMV de California anunci\u00f3 que durante los primeros seis meses de este a\u00f1o los inmigrantes indocumentados obtuvieron casi 400 mil licencias de conducir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"DMV ha otorgado 400 mil licencias a indocumentados","og_description":"El DMV de California anunci\u00f3 que durante los primeros seis meses de este a\u00f1o los inmigrantes indocumentados obtuvieron casi 400 mil licencias de conducir.","og_url":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-07-20T16:55:33+00:00","article_modified_time":"2025-10-30T04:39:05+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"DMV ha otorgado 400 mil licencias a indocumentados","datePublished":"2015-07-20T16:55:33+00:00","dateModified":"2025-10-30T04:39:05+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/"},"wordCount":234,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/","name":"DMV ha otorgado 400 mil licencias a indocumentados","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-07-20T16:55:33+00:00","dateModified":"2025-10-30T04:39:05+00:00","description":"El DMV de California anunci\u00f3 que durante los primeros seis meses de este a\u00f1o los inmigrantes indocumentados obtuvieron casi 400 mil licencias de conducir.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/dmv-ha-otorgado-400-mil-licencias-a-indocumentados\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"DMV ha otorgado 400 mil licencias a indocumentados"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/1706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=1706"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/1706\/revisions"}],"predecessor-version":[{"id":68252,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/1706\/revisions\/68252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=1706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=1706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=1706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}