{"id":15957,"date":"2018-12-13T09:39:32","date_gmt":"2018-12-13T15:39:32","guid":{"rendered":"https:\/\/accesolatino.org\/?p=15957"},"modified":"2025-11-13T21:54:21","modified_gmt":"2025-11-14T03:54:21","slug":"convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/noticias\/","title":{"rendered":"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"15957\" class=\"elementor elementor-15957 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-369f77a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"369f77a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ef62e2\" data-id=\"8ef62e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9121ee elementor-widget elementor-widget-text-editor\" data-id=\"d9121ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfEres maestro mexicano, hablas ingl\u00e9s y te gustar\u00eda trabajar en Estados Unidos? El <a href=\"http:\/\/www.dgri.sep.gob.mx\/probem.html\"><strong>Instituto de los Mexicanos en el Exterior (IME) <\/strong><\/a>abri\u00f3 la <a href=\"http:\/\/www.dgri.sep.gob.mx\/formatos\/probem\/CEP2019.pdf\"><strong>convocatoria <\/strong><\/a>para el programa de Intercambio de Maestros M\u00e9xico-Estados Unidos.<\/p><p>Los maestros aceptados en el programa viajar\u00e1n a Estados Unidos, por un periodo de tres a ocho semanas, para \u201cfortalecer los procesos educativos de los estudiantes de ambos pa\u00edses\u201d.<\/p><p>A trav\u00e9s de un comunicado, el IME informa que tambi\u00e9n ser\u00e1 un intercambio cultural. Los maestros mexicanos profundizar\u00e1n en la historia, cultura y valores del pa\u00eds, a trav\u00e9s de la lectura, la escritura, matem\u00e1ticas, ciencias e historia. En especial, con alumnos de origen mexicano.<\/p><p>La Comisi\u00f3n de Intercambio del Consejo Mexicano del PROBEM se encargar\u00e1 de asignar los espacios a los profesores que registren su solicitud.<\/p><p>Primero se realizar\u00e1 una preselecci\u00f3n en cada entidad. Los candidatos ser\u00e1n entrevistados por representantes de los Distritos Escolares para seleccionar los mejores perfiles.<\/p><p>Quienes sean \u201cpre-aprobados\u201d deber\u00e1n asistir al Seminario Nacional de Capacitaci\u00f3n y firmar una carta compromiso. La DGRI aprobar\u00e1 el listado final.<\/p><p>La convocatoria est\u00e1 abierta hasta el 31 de diciembre de 2018. Los seleccionados deber\u00e1n tramitar su visa de intercambio J1 a partir del 8 de abril de 2019 para poder participar en el intercambio de mayo a agosto.<\/p><p>Las autoridades mexicanas cubrir\u00e1n el costo del traslado a\u00e9reo de ida y vuelta; tambi\u00e9n un seguro de vida. Est\u00e1n obligadas a realizar un acompa\u00f1amiento con los docentes. Tendr\u00e1n cubierta su estancia, alimentaci\u00f3n y transporte local.<\/p><p>Aqu\u00ed te dejamos los requisitos necesarios para participar en la convocatoria:<\/p><ul><li>Ser de nacionalidad mexicana, tener pasaporte vigente al 31 de diciembre de 2019 y no tener antecedentes penales.<\/li><li>Contar con t\u00edtulo de licenciatura en Educaci\u00f3n.<\/li><li>Ejercer como docente en educaci\u00f3n preescolar, primaria, secundaria, media superior, ind\u00edgena y maestros del Programa Nacional de Ingl\u00e9s.<\/li><li>Contar con plaza base.<\/li><li>Contar con experiencia m\u00ednima de tres a\u00f1os frente a grupo.<\/li><li>Tener disponibilidad para ausentarse del pa\u00eds de tres a ocho semanas.<\/li><\/ul><p>In <strong>Acceso Latino<\/strong> nos ocupamos por acercarte toda la informaci\u00f3n de utilidad en tu calidad de inmigrante. Mantente al tanto con nuestras noticias y haz uso de las herramientas en l\u00ednea totalmente gratuitas que tenemos para ti en distintos rubros como <a href=\"https:\/\/accesolatino.org\/en\/buscas-empleo\/\"><strong>empleo<\/strong><\/a>, <a href=\"https:\/\/accesolatino.org\/en\/orientacion-legal\/\"><strong>orientaci\u00f3n legal<\/strong><\/a>, <a href=\"https:\/\/accesolatino.org\/en\/salud\/\"><strong>salud<\/strong><\/a>, <a href=\"https:\/\/accesolatino.org\/en\/educacion\/\"><strong>educaci\u00f3n<\/strong> <\/a>and <a href=\"https:\/\/accesolatino.org\/en\/conoce-y-protege-tus-derechos-laborales-basicos\/derecho\/\"><strong>derechos humanos<\/strong><\/a>. Para hacer uso de ellas tienes que ingresar a accesolatino.org<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfEres maestro mexicano, hablas ingl\u00e9s y te gustar\u00eda trabajar en Estados Unidos? El Instituto de los Mexicanos en el Exterior (IME) abri\u00f3 la convocatoria para el programa de Intercambio de Maestros M\u00e9xico-Estados Unidos. Los maestros aceptados en el programa viajar\u00e1n a Estados Unidos, por un periodo de tres a ocho semanas, para \u201cfortalecer los procesos educativos de los estudiantes de ambos pa\u00edses\u201d. A trav\u00e9s de un comunicado, el IME informa que tambi\u00e9n ser\u00e1 un intercambio cultural. Los maestros mexicanos profundizar\u00e1n en la historia, cultura y valores del pa\u00eds, a trav\u00e9s de la lectura, la escritura, matem\u00e1ticas, ciencias e historia. En especial, con alumnos de origen mexicano. La Comisi\u00f3n de Intercambio del Consejo Mexicano del PROBEM se encargar\u00e1 de asignar los espacios a los profesores que registren su solicitud. Primero se realizar\u00e1 una preselecci\u00f3n en cada entidad. Los candidatos ser\u00e1n entrevistados por representantes de los Distritos Escolares para seleccionar los mejores perfiles. Quienes sean \u201cpre-aprobados\u201d deber\u00e1n asistir al Seminario Nacional de Capacitaci\u00f3n y firmar una carta compromiso. La DGRI aprobar\u00e1 el listado final. La convocatoria est\u00e1 abierta hasta el 31 de diciembre de 2018. Los seleccionados deber\u00e1n tramitar su visa de intercambio J1 a partir del 8 de abril de 2019 para poder participar en el intercambio de mayo a agosto. Las autoridades mexicanas cubrir\u00e1n el costo del traslado a\u00e9reo de ida y vuelta; tambi\u00e9n un seguro de vida. Est\u00e1n obligadas a realizar un acompa\u00f1amiento con los docentes. Tendr\u00e1n cubierta su estancia, alimentaci\u00f3n y transporte local. Aqu\u00ed te dejamos los requisitos necesarios para participar en la convocatoria: Ser de nacionalidad mexicana, tener pasaporte vigente al 31 de diciembre de 2019 y no tener antecedentes penales. Contar con t\u00edtulo de licenciatura en Educaci\u00f3n. Ejercer como docente en educaci\u00f3n preescolar, primaria, secundaria, media superior, ind\u00edgena y maestros del Programa Nacional de Ingl\u00e9s. Contar con plaza base. Contar con experiencia m\u00ednima de tres a\u00f1os frente a grupo. Tener disponibilidad para ausentarse del pa\u00eds de tres a ocho semanas. En Acceso Latino nos ocupamos por acercarte toda la informaci\u00f3n de utilidad en tu calidad de inmigrante. Mantente al tanto con nuestras noticias y haz uso de las herramientas en l\u00ednea totalmente gratuitas que tenemos para ti en distintos rubros como empleo, orientaci\u00f3n legal, salud, educaci\u00f3n y derechos humanos. Para hacer uso de ellas tienes que ingresar a accesolatino.org<\/p>","protected":false},"author":13,"featured_media":15958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-15957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA<\/title>\n<meta name=\"description\" content=\"\u00bfEres maestro mexicano, hablas ingl\u00e9s y te gustar\u00eda trabajar en Estados Unidos? El (IME) para el programa de Intercambio de Maestros M\u00e9xico-Estados Unidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA\" \/>\n<meta property=\"og:description\" content=\"\u00bfEres maestro mexicano, hablas ingl\u00e9s y te gustar\u00eda trabajar en Estados Unidos? El (IME) para el programa de Intercambio de Maestros M\u00e9xico-Estados Unidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-13T15:39:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T03:54:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/12\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA\",\"datePublished\":\"2018-12-13T15:39:32+00:00\",\"dateModified\":\"2025-11-14T03:54:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/\"},\"wordCount\":429,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/\",\"name\":\"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg\",\"datePublished\":\"2018-12-13T15:39:32+00:00\",\"dateModified\":\"2025-11-14T03:54:21+00:00\",\"description\":\"\u00bfEres maestro mexicano, hablas ingl\u00e9s y te gustar\u00eda trabajar en Estados Unidos? El (IME) para el programa de Intercambio de Maestros M\u00e9xico-Estados Unidos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg\",\"width\":600,\"height\":338,\"caption\":\"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA","description":"\u00bfEres maestro mexicano, hablas ingl\u00e9s y te gustar\u00eda trabajar en Estados Unidos? El (IME) para el programa de Intercambio de Maestros M\u00e9xico-Estados Unidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA","og_description":"\u00bfEres maestro mexicano, hablas ingl\u00e9s y te gustar\u00eda trabajar en Estados Unidos? El (IME) para el programa de Intercambio de Maestros M\u00e9xico-Estados Unidos.","og_url":"https:\/\/accesolatino.org\/en\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2018-12-13T15:39:32+00:00","article_modified_time":"2025-11-14T03:54:21+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/12\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA","datePublished":"2018-12-13T15:39:32+00:00","dateModified":"2025-11-14T03:54:21+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/"},"wordCount":429,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/12\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/","name":"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/12\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg","datePublished":"2018-12-13T15:39:32+00:00","dateModified":"2025-11-14T03:54:21+00:00","description":"\u00bfEres maestro mexicano, hablas ingl\u00e9s y te gustar\u00eda trabajar en Estados Unidos? El (IME) para el programa de Intercambio de Maestros M\u00e9xico-Estados Unidos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/12\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/12\/Convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-EUA.jpg","width":600,"height":338,"caption":"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/convocatoria-del-gobierno-mexicano-para-maestros-que-hablen-ingles-y-quieran-trabajar-en-eua\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Convocatoria del gobierno mexicano para maestros que hablen ingl\u00e9s y quieran trabajar en EUA"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/15957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=15957"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/15957\/revisions"}],"predecessor-version":[{"id":68731,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/15957\/revisions\/68731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/15958"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=15957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=15957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=15957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}