{"id":12454,"date":"2016-05-25T11:55:42","date_gmt":"2016-05-25T16:55:42","guid":{"rendered":"https:\/\/accesolatino.org\/?p=4047"},"modified":"2025-10-29T09:51:31","modified_gmt":"2025-10-29T15:51:31","slug":"varicela-problema-mas-enfrentan-inmigrantes-centros-detencion","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/","title":{"rendered":"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n"},"content":{"rendered":"<p>Autoridades de la Oficina de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s) informaron el pasado 24 de mayo que <strong>el centro de detenci\u00f3n para inmigrantes indocumentados en Eloy, Arizona, sufre un brote de varicela, por lo que las visitas han sido suspendidas<\/strong>.<\/p>\n<p>De acuerdo con la agencia federal, <strong>hay cuatro personas infectadas de varicela en este centro de detenci\u00f3n y, por lo menos, otras 16 personas se encuentran bajo vigilancia m\u00e9dica<\/strong>, ya que pudieron haber sido expuestos a esta enfermedad contagiosa.<\/p>\n<p>Ante el anuncio, <strong>Puente, grupo de defensa de los derechos humanos con sede en Phoenix, calific\u00f3 en su p\u00e1gina de Facebook este brote de varicela como \u201cuna crisis de salud\u201d y estiman que al menos 800 inmigrantes detenidos est\u00e1n en cuarentena<\/strong>, alejados del resto de la poblaci\u00f3n reclusa del centro de detenci\u00f3n.<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/\" target=\"_blank\" rel=\"noopener\">Conoce m\u00e1s: 9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes<\/a><\/span><\/strong><\/p>\n<p>El grupo de activistas inst\u00f3 a ICE que deje de enviar a inmigrantes indocumentados al centro de detenci\u00f3n de Eloy mientras pasa el contagio de varicela. Y agreg\u00f3 que todas las personas contagiadas sean enviadas a un hospital.<\/p>\n<p>Asimismo, Puente denuncia que algunos de los detenidos han reportado que solo reciben una comida al d\u00eda y escasa atenci\u00f3n m\u00e9dica. \u201cEl centro de Eloy es considerado uno de los m\u00e1s peligrosos en el pa\u00eds\u201d, dijo Carlos Garc\u00eda, director del grupo activista.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>EFE<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Autoridades de la Oficina de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s) informaron el pasado 24 de mayo que el centro de detenci\u00f3n para inmigrantes indocumentados en Eloy, Arizona, sufre un brote de varicela, por lo que las visitas han sido suspendidas. De acuerdo con la agencia federal, hay cuatro personas infectadas de varicela en este centro de detenci\u00f3n y, por lo menos, otras 16 personas se encuentran bajo vigilancia m\u00e9dica, ya que pudieron haber sido expuestos a esta enfermedad contagiosa. Ante el anuncio, Puente, grupo de defensa de los derechos humanos con sede en Phoenix, calific\u00f3 en su p\u00e1gina de Facebook este brote de varicela como \u201cuna crisis de salud\u201d y estiman que al menos 800 inmigrantes detenidos est\u00e1n en cuarentena, alejados del resto de la poblaci\u00f3n reclusa del centro de detenci\u00f3n. Conoce m\u00e1s: 9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes El grupo de activistas inst\u00f3 a ICE que deje de enviar a inmigrantes indocumentados al centro de detenci\u00f3n de Eloy mientras pasa el contagio de varicela. Y agreg\u00f3 que todas las personas contagiadas sean enviadas a un hospital. Asimismo, Puente denuncia que algunos de los detenidos han reportado que solo reciben una comida al d\u00eda y escasa atenci\u00f3n m\u00e9dica. \u201cEl centro de Eloy es considerado uno de los m\u00e1s peligrosos en el pa\u00eds\u201d, dijo Carlos Garc\u00eda, director del grupo activista. &nbsp; Fuente: EFE<\/p>","protected":false},"author":13,"featured_media":2685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n<\/title>\n<meta name=\"description\" content=\"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-25T16:55:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T15:51:31+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n\",\"datePublished\":\"2016-05-25T16:55:42+00:00\",\"dateModified\":\"2025-10-29T15:51:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/\"},\"wordCount\":257,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/\",\"name\":\"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-05-25T16:55:42+00:00\",\"dateModified\":\"2025-10-29T15:51:31+00:00\",\"description\":\"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n","description":"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n","og_description":"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n","og_url":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-05-25T16:55:42+00:00","article_modified_time":"2025-10-29T15:51:31+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n","datePublished":"2016-05-25T16:55:42+00:00","dateModified":"2025-10-29T15:51:31+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/"},"wordCount":257,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/","url":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/","name":"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-05-25T16:55:42+00:00","dateModified":"2025-10-29T15:51:31+00:00","description":"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/varicela-problema-mas-enfrentan-inmigrantes-centros-detencion\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Varicela, un problema m\u00e1s que enfrentan inmigrantes en centros de detenci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12454"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12454\/revisions"}],"predecessor-version":[{"id":67677,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12454\/revisions\/67677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}