{"id":12427,"date":"2016-05-08T11:55:59","date_gmt":"2016-05-08T16:55:59","guid":{"rendered":"https:\/\/accesolatino.org\/?p=3930"},"modified":"2025-10-29T10:10:17","modified_gmt":"2025-10-29T16:10:17","slug":"9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/","title":{"rendered":"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes"},"content":{"rendered":"<p>Los centros de detenci\u00f3n para inmigrantes son una medida muy pol\u00e9mica en Estados Unidos, pues son considerados una especie de &#8220;c\u00e1rcel&#8221; por parte de activistas, mientras que el gobierno se encarga de afirmar que no se violan los derechos humanos de las personas en ning\u00fan momento.<\/p>\n<p>En el pa\u00eds hay por lo menos un centro de detenci\u00f3n de inmigrantes indocumentados en cada estado y no hay un periodo de tiempo en que una persona permanece en \u00e9l hasta que su caso sea resuelto, ya sea por medio del cumplimiento de una orden de deportaci\u00f3n o librado porque el individuo encontr\u00f3 una v\u00eda legal para permanecer en el pa\u00eds.<\/p>\n<p>A continuaci\u00f3n te presentamos los aspectos clave sobre estos pol\u00e9micos centros de detenci\u00f3n:<\/p>\n<p>1. Un informe del Transactional Records Access Clearinghouse (TRAC) de la Universidad Siracuse, Nueva York, detalla que<strong> el sistema de detenci\u00f3n de inmigrantes indocumentados del gobierno federal utiliz\u00f3 637 centros de este tipo durante el a\u00f1o fiscal 2015<\/strong>.<\/p>\n<p>2. No todos estos centros son operados por la Oficina de Inmigraci\u00f3n y Aduanas (ICE). En 2015, <strong>la mayor\u00eda de ellos fueron manejados por empresas privadas<\/strong>.<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/dhs-realizara-visitas-inspeccion-no-anunciadas-centros-detencion-del-ice\/\" target=\"_blank\" rel=\"noopener\">Conoce m\u00e1s: DHS realizar\u00e1 visitas de inspecci\u00f3n no anunciadas a centros de detenci\u00f3n del ICE<\/a><\/span><\/strong><\/p>\n<p>3. <strong>Los inmigrantes detenidos no permanecen en un mismo centro<\/strong>. Un gran n\u00famero de ellos \u201ccontinuamente est\u00e1n siendo transferidos\u201d entre las instalaciones.<\/p>\n<p>4. Seg\u00fan el TRAC,<strong> durante el a\u00f1o fiscal 2015 se registraron un total de 325 mil 209 inmigrantes detenidos en estos centros<\/strong>. De ellos, 39 mil 82 siguieron detenidos en el 2016.<\/p>\n<p>5. <strong>El 55% de los inmigrantes detenidos fue deportado<\/strong>. Otros fueron liberados bajo fianza y algunos concluyeron sus procesos porque hallaron una forma para permanecer en el pa\u00eds.<\/p>\n<p>6. El TRAC se\u00f1ala que <strong>la mayor\u00eda de los centros se concentraron a lo largo de la frontera suroeste con M\u00e9xico<\/strong>, y que al menos un centro opera en cada uno de los 50 estados o estados asociados, incluyendo a Puerto Rico, Guam, Islas V\u00edrgenes e Islas marianas del Norte.<\/p>\n<p>7. <strong>Algunos centros son de estad\u00eda temporal (72 horas m\u00e1ximo) y otros fueron dise\u00f1ados para \u201cestancias de largo tiempo\u201d<\/strong>. Algunos indocumentados han permanecido por m\u00e1s de un a\u00f1o detenidos antes de ser deportados o liberados.<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/cbp-anuncia-mejores-condiciones-para-inmigrantes-en-centros-de-detencion\/\" target=\"_blank\" rel=\"noopener\">Conoce m\u00e1s: CBP anuncia mejores condiciones para inmigrantes en centros de detenci\u00f3n<\/a><\/span><\/strong><\/p>\n<p>8. <strong>M\u00e1s de la mitad de los indocumentados bajo custodia de ICE (55%) fueron arrestados y trasladados a la agencia por la Patrulla Fronteriza (Border Patrol)<\/strong>. Poco m\u00e1s del 11% fue detenido por agentes de ICE y apenas el 0.2% fue capturado bajo el Programa Federal 287(g) que otorga poderes especiales a las polic\u00edas locales para que sus agentes arresten a indocumentados.<\/p>\n<p>9. El TRAC revel\u00f3 que las cortes de inmigraci\u00f3n alcanzaron, a finales de marzo, dos nuevos r\u00e9cords: uno de casos acumulados y otro de tiempos de espera. <strong>Al 30 de marzo hab\u00eda 486 mil 206 casos pendientes en los tribunales<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>Univisi\u00f3n, La Opini\u00f3n<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Los centros de detenci\u00f3n para inmigrantes son una medida muy pol\u00e9mica en Estados Unidos, pues son considerados una especie de &#8220;c\u00e1rcel&#8221; por parte de activistas, mientras que el gobierno se encarga de afirmar que no se violan los derechos humanos de las personas en ning\u00fan momento. En el pa\u00eds hay por lo menos un centro de detenci\u00f3n de inmigrantes indocumentados en cada estado y no hay un periodo de tiempo en que una persona permanece en \u00e9l hasta que su caso sea resuelto, ya sea por medio del cumplimiento de una orden de deportaci\u00f3n o librado porque el individuo encontr\u00f3 una v\u00eda legal para permanecer en el pa\u00eds. A continuaci\u00f3n te presentamos los aspectos clave sobre estos pol\u00e9micos centros de detenci\u00f3n: 1. Un informe del Transactional Records Access Clearinghouse (TRAC) de la Universidad Siracuse, Nueva York, detalla que el sistema de detenci\u00f3n de inmigrantes indocumentados del gobierno federal utiliz\u00f3 637 centros de este tipo durante el a\u00f1o fiscal 2015. 2. No todos estos centros son operados por la Oficina de Inmigraci\u00f3n y Aduanas (ICE). En 2015, la mayor\u00eda de ellos fueron manejados por empresas privadas. Conoce m\u00e1s: DHS realizar\u00e1 visitas de inspecci\u00f3n no anunciadas a centros de detenci\u00f3n del ICE 3. Los inmigrantes detenidos no permanecen en un mismo centro. Un gran n\u00famero de ellos \u201ccontinuamente est\u00e1n siendo transferidos\u201d entre las instalaciones. 4. Seg\u00fan el TRAC, durante el a\u00f1o fiscal 2015 se registraron un total de 325 mil 209 inmigrantes detenidos en estos centros. De ellos, 39 mil 82 siguieron detenidos en el 2016. 5. El 55% de los inmigrantes detenidos fue deportado. Otros fueron liberados bajo fianza y algunos concluyeron sus procesos porque hallaron una forma para permanecer en el pa\u00eds. 6. El TRAC se\u00f1ala que la mayor\u00eda de los centros se concentraron a lo largo de la frontera suroeste con M\u00e9xico, y que al menos un centro opera en cada uno de los 50 estados o estados asociados, incluyendo a Puerto Rico, Guam, Islas V\u00edrgenes e Islas marianas del Norte. 7. Algunos centros son de estad\u00eda temporal (72 horas m\u00e1ximo) y otros fueron dise\u00f1ados para \u201cestancias de largo tiempo\u201d. Algunos indocumentados han permanecido por m\u00e1s de un a\u00f1o detenidos antes de ser deportados o liberados. Conoce m\u00e1s: CBP anuncia mejores condiciones para inmigrantes en centros de detenci\u00f3n 8. M\u00e1s de la mitad de los indocumentados bajo custodia de ICE (55%) fueron arrestados y trasladados a la agencia por la Patrulla Fronteriza (Border Patrol). Poco m\u00e1s del 11% fue detenido por agentes de ICE y apenas el 0.2% fue capturado bajo el Programa Federal 287(g) que otorga poderes especiales a las polic\u00edas locales para que sus agentes arresten a indocumentados. 9. El TRAC revel\u00f3 que las cortes de inmigraci\u00f3n alcanzaron, a finales de marzo, dos nuevos r\u00e9cords: uno de casos acumulados y otro de tiempos de espera. Al 30 de marzo hab\u00eda 486 mil 206 casos pendientes en los tribunales. &nbsp; Fuente: Univisi\u00f3n, La Opini\u00f3n<\/p>","protected":false},"author":13,"featured_media":3932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-12427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes<\/title>\n<meta name=\"description\" content=\"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes\" \/>\n<meta property=\"og:description\" content=\"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-08T16:55:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T16:10:17+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes\",\"datePublished\":\"2016-05-08T16:55:59+00:00\",\"dateModified\":\"2025-10-29T16:10:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/\"},\"wordCount\":512,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Comunidad\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/\",\"name\":\"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-05-08T16:55:59+00:00\",\"dateModified\":\"2025-10-29T16:10:17+00:00\",\"description\":\"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\\\/comunidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunidad\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/comunidad\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes","description":"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/","og_locale":"en_US","og_type":"article","og_title":"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes","og_description":"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes","og_url":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-05-08T16:55:59+00:00","article_modified_time":"2025-10-29T16:10:17+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes","datePublished":"2016-05-08T16:55:59+00:00","dateModified":"2025-10-29T16:10:17+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/"},"wordCount":512,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/#primaryimage"},"thumbnailUrl":"","articleSection":["Comunidad"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/","url":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/","name":"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-05-08T16:55:59+00:00","dateModified":"2025-10-29T16:10:17+00:00","description":"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/9-aspectos-clave-sobre-los-centros-de-detencion-de-inmigrantes\/comunidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Comunidad","item":"https:\/\/accesolatino.org\/category\/comunidad\/"},{"@type":"ListItem","position":3,"name":"9 aspectos clave sobre los centros de detenci\u00f3n de inmigrantes"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12427"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12427\/revisions"}],"predecessor-version":[{"id":67705,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12427\/revisions\/67705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}