{"id":12362,"date":"2016-03-26T11:55:00","date_gmt":"2016-03-26T17:55:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=3487"},"modified":"2025-10-29T14:07:57","modified_gmt":"2025-10-29T20:07:57","slug":"washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/","title":{"rendered":"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>El d\u00eda de hoy (26 marzo) se lleva a cabo la treceava jornada electoral en Estados Unidos para determinar a los candidatos presidenciales del Partido Republicano y Dem\u00f3crata, en este d\u00eda toca el turno de Washington, Alaska y Hawai<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Tras la pasada jornada del 22 de marzo (<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/hoy-votan-arizona-idaho-y-utah-como-va-la-carrera-para-la-presidencia\/\" target=\"_blank\" rel=\"noopener\">donde hubo votaciones en Arizona, Idaho y Utah<\/a><\/span>), este d\u00eda tambi\u00e9n habr\u00e1 votaciones en tres estados, sin embargo, <strong>en esta ocasi\u00f3n solamente se votar\u00e1 en el bando dem\u00f3crata<\/strong>, pues los republicanos ya han llevado a cabo su votaci\u00f3n en dos de estos lugares (Alaska 1 de marzo y Hawai 8 de marzo), mientras que en Washington ser\u00e1 hasta el pr\u00f3ximo 24 de mayo.<\/p>\n<p style=\"text-align: justify;\">Las votaciones actualmente en el Partido Dem\u00f3crata son lideradas por Hillary Clinton, con 1,691 delegados ganados, seguida de <em>Bernie<\/em> Sanders, con 949 delegados ganados; se necesitan 2,383 delegados para obtener la nominaci\u00f3n dem\u00f3crata.<\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n te presentamos las claves de la votaci\u00f3n para estos tres estados:<\/p>\n<p style=\"text-align: justify;\"><strong>Washington.-<\/strong> Habr\u00e1 101 delegados en juego. El condado de King, el hogar de m\u00e1s de 2 millones de personas, ser\u00e1 un referente, ya que posee la ciudad m\u00e1s grande del estado, Seattle y la Universidad de Washington, la m\u00e1s grande del estado. Snohomish y Pierce son los grandes condados suburbanos al norte y al sur. Yakima y Grant son condados con grandes poblaciones hispanas, cada uno es de 40% o m\u00e1s hispana. Datos oficiales calculan que hay 7 millones 62 mil habitantes en el estado, de los cuales 858 mil son hispanos.<\/p>\n<p style=\"text-align: justify;\"><strong>Hawai.-<\/strong> Adjudicar\u00e1 25 delegados. Ninguno de los dos candidatos tienen particularmente fuertes lazos con el estado, uno de los m\u00e1s pol\u00edticamente liberales en el pa\u00eds. El condado de Honolulu es el m\u00e1s densamente poblado de la cadena de islas, que posee el 70% de su poblaci\u00f3n y es el hogar de la capital del estado. Es muy diverso, menos del 20% de su poblaci\u00f3n es blanca, no hispanos, pero el n\u00facleo de su diversidad es una enorme poblaci\u00f3n de origen asi\u00e1tico. M\u00e1s de 40% de la poblaci\u00f3n es asi\u00e1tica. Datos oficiales calculan que hay 1 mill\u00f3n 420 mil habitantes en el estado, de los cuales 142 mil son hispanos.<\/p>\n<p style=\"text-align: justify;\"><strong>Alaska.-<\/strong> Adjudicar\u00e1 16 delegados. No tiene grandes poblaciones afroamericanas o hispanas. Conseguir una lectura sobre la geograf\u00eda de la votaci\u00f3n en Alaska ser\u00e1 dif\u00edcil. Los resultados en Alaska no son reportados por condado, sino m\u00e1s bien por los distritos del estado. Datos oficiales calculan que hay 737 mil habitantes en el estado, de los cuales 49 mil son hispanos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Fuente: <em>The Wall Street Journal, Univisi\u00f3n<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>El d\u00eda de hoy (26 marzo) se lleva a cabo la treceava jornada electoral en Estados Unidos para determinar a los candidatos presidenciales del Partido Republicano y Dem\u00f3crata, en este d\u00eda toca el turno de Washington, Alaska y Hawai. Tras la pasada jornada del 22 de marzo (donde hubo votaciones en Arizona, Idaho y Utah), este d\u00eda tambi\u00e9n habr\u00e1 votaciones en tres estados, sin embargo, en esta ocasi\u00f3n solamente se votar\u00e1 en el bando dem\u00f3crata, pues los republicanos ya han llevado a cabo su votaci\u00f3n en dos de estos lugares (Alaska 1 de marzo y Hawai 8 de marzo), mientras que en Washington ser\u00e1 hasta el pr\u00f3ximo 24 de mayo. Las votaciones actualmente en el Partido Dem\u00f3crata son lideradas por Hillary Clinton, con 1,691 delegados ganados, seguida de Bernie Sanders, con 949 delegados ganados; se necesitan 2,383 delegados para obtener la nominaci\u00f3n dem\u00f3crata. A continuaci\u00f3n te presentamos las claves de la votaci\u00f3n para estos tres estados: Washington.- Habr\u00e1 101 delegados en juego. El condado de King, el hogar de m\u00e1s de 2 millones de personas, ser\u00e1 un referente, ya que posee la ciudad m\u00e1s grande del estado, Seattle y la Universidad de Washington, la m\u00e1s grande del estado. Snohomish y Pierce son los grandes condados suburbanos al norte y al sur. Yakima y Grant son condados con grandes poblaciones hispanas, cada uno es de 40% o m\u00e1s hispana. Datos oficiales calculan que hay 7 millones 62 mil habitantes en el estado, de los cuales 858 mil son hispanos. Hawai.- Adjudicar\u00e1 25 delegados. Ninguno de los dos candidatos tienen particularmente fuertes lazos con el estado, uno de los m\u00e1s pol\u00edticamente liberales en el pa\u00eds. El condado de Honolulu es el m\u00e1s densamente poblado de la cadena de islas, que posee el 70% de su poblaci\u00f3n y es el hogar de la capital del estado. Es muy diverso, menos del 20% de su poblaci\u00f3n es blanca, no hispanos, pero el n\u00facleo de su diversidad es una enorme poblaci\u00f3n de origen asi\u00e1tico. M\u00e1s de 40% de la poblaci\u00f3n es asi\u00e1tica. Datos oficiales calculan que hay 1 mill\u00f3n 420 mil habitantes en el estado, de los cuales 142 mil son hispanos. Alaska.- Adjudicar\u00e1 16 delegados. No tiene grandes poblaciones afroamericanas o hispanas. Conseguir una lectura sobre la geograf\u00eda de la votaci\u00f3n en Alaska ser\u00e1 dif\u00edcil. Los resultados en Alaska no son reportados por condado, sino m\u00e1s bien por los distritos del estado. Datos oficiales calculan que hay 737 mil habitantes en el estado, de los cuales 49 mil son hispanos. Fuente: The Wall Street Journal, Univisi\u00f3n<\/p>","protected":false},"author":13,"featured_media":3488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy<\/title>\n<meta name=\"description\" content=\"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy\" \/>\n<meta property=\"og:description\" content=\"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-26T17:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T20:07:57+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy\",\"datePublished\":\"2016-03-26T17:55:00+00:00\",\"dateModified\":\"2025-10-29T20:07:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/\"},\"wordCount\":450,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/\",\"name\":\"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-03-26T17:55:00+00:00\",\"dateModified\":\"2025-10-29T20:07:57+00:00\",\"description\":\"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy","description":"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy","og_description":"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy","og_url":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-03-26T17:55:00+00:00","article_modified_time":"2025-10-29T20:07:57+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy","datePublished":"2016-03-26T17:55:00+00:00","dateModified":"2025-10-29T20:07:57+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/"},"wordCount":450,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/","url":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/","name":"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-03-26T17:55:00+00:00","dateModified":"2025-10-29T20:07:57+00:00","description":"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/washington-alaska-y-hawai-van-a-las-urnas-el-dia-de-hoy\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Washington, Alaska y Hawai van a las urnas el d\u00eda de hoy"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12362"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12362\/revisions"}],"predecessor-version":[{"id":67808,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12362\/revisions\/67808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}