{"id":12347,"date":"2016-03-16T16:55:55","date_gmt":"2016-03-16T22:55:55","guid":{"rendered":"https:\/\/accesolatino.org\/?p=3404"},"modified":"2025-10-29T14:06:02","modified_gmt":"2025-10-29T20:06:02","slug":"jose-hernandez-el-nino-que-toco-las-estrellas","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/","title":{"rendered":"Jos\u00e9 Hern\u00e1ndez: &#8216;El ni\u00f1o que toc\u00f3 las estrellas&#8217;"},"content":{"rendered":"<p>A pesar que en el acta de nacimiento de <strong>Jos\u00e9 Hern\u00e1ndez Moreno<\/strong> diga que naci\u00f3 en French Camp, California, los or\u00edgenes del ahora famoso astronauta se encuentran a miles de kil\u00f3metros hacia el sur: en Michoac\u00e1n, M\u00e9xico.<\/p>\n<p>El municipio de La Piedad, Michoac\u00e1n fue el lugar donde naci\u00f3 el se\u00f1or Samuel Hern\u00e1ndez, padre de <strong>Jos\u00e9<\/strong>, quien, cuando decidi\u00f3 emprender su viaje hacia Estados Unidos, seguramente no imagin\u00f3 que su futuro hijo, al igual que \u00e9l, emprender\u00eda un viaje largo y peligroso; solo que \u00e9l no lo har\u00eda pensando en un mejor porvenir para su familia, sino teniendo en mente cumplir su m\u00e1s grande sue\u00f1o: tocar las estrellas.<\/p>\n<p>\u201cMe cambi\u00f3 la vida ir al espacio\u201d, admite <strong>Jos\u00e9 Hern\u00e1ndez<\/strong>, quien en dos ocasiones ha tenido la oportunidad de ver al planeta Tierra desde el espacio. \u201cDoce veces lo intent\u00e9 y lo logr\u00e9. Ver la Tierra desde otra perspectiva tiene un impacto profundo en ti\u201d, comparte quien, cuando era ni\u00f1o, ayudaba a su padre en las cosechas, viajando desde el sur de California hasta Michoac\u00e1n cada mes de marzo.<\/p>\n<p>Y fue uno de sos d\u00edas durante su dura infancia cuando fue testigo del suceso que lo llevar\u00eda a fijar su meta en la vida. \u201cMe encontraba limpiando con azad\u00f3n una fila de remolacha azucarera en un campo de cultivo cerca de Stockton, California y escuch\u00e9 en la radio de transistores que Franklin Chang-D\u00edaz hab\u00eda sido seleccionado como astronauta\u2026 y all\u00ed fue cuando me naci\u00f3 el sue\u00f1o de querer ser astronauta\u201d, narra y, como cualquier ni\u00f1o que acaba de encontrar su meta en la vida, corri\u00f3 a cont\u00e1rselo a su padre, quien, lejos de hacerle ver lo imposible que aquello sonaba, \u201cme dio una receta muy simple para llegar a cumplirla (su meta)\u201d.<\/p>\n<p>\u201cMe sent\u00f3 en la mesa de la cocina y me dijo que si quer\u00eda ser astronauta siguiera estos pasos: \u2018<strong>Define tu meta; reconoce qu\u00e9 tan lejos est\u00e1s de esa meta; crea una ruta o plan que te va a llevar a cumplir tu sue\u00f1o; ed\u00facate, pues no hay sustituto para llegar a la meta sin una buena educaci\u00f3n; y finalmente ten ganas y perseverancia<\/strong>&#8216;\u201d, el peque\u00f1o Jos\u00e9 escuch\u00f3 con atenci\u00f3n y sigui\u00f3 cada uno de esos pasos; tras a\u00f1os de perseverancia y esfuerzo, pudo tocar las estrellas.<\/p>\n<p>\u201cYo vine de una familia muy pobre, muy humilde, de familia inmigrante campesina y este pa\u00eds me dio la oportunidad de estudiar y perseguir mis sue\u00f1os como astronauta\u201d, dice orgulloso <strong>Jos\u00e9 Hern\u00e1ndez<\/strong>, quien actualmente se encuentra promoviendo un libro que decidi\u00f3 escribir dise\u00f1ado para ni\u00f1os, titulado <em>El ni\u00f1o que toc\u00f3 las estrellas<\/em>, el cual es su segunda obra, siendo la primera <em>Cosechador de estrellas<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>NASA, Exc\u00e9lsior, Radio F\u00f3rmula<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>A pesar que en el acta de nacimiento de Jos\u00e9 Hern\u00e1ndez Moreno diga que naci\u00f3 en French Camp, California, los or\u00edgenes del ahora famoso astronauta se encuentran a miles de kil\u00f3metros hacia el sur: en Michoac\u00e1n, M\u00e9xico. El municipio de La Piedad, Michoac\u00e1n fue el lugar donde naci\u00f3 el se\u00f1or Samuel Hern\u00e1ndez, padre de Jos\u00e9, quien, cuando decidi\u00f3 emprender su viaje hacia Estados Unidos, seguramente no imagin\u00f3 que su futuro hijo, al igual que \u00e9l, emprender\u00eda un viaje largo y peligroso; solo que \u00e9l no lo har\u00eda pensando en un mejor porvenir para su familia, sino teniendo en mente cumplir su m\u00e1s grande sue\u00f1o: tocar las estrellas. \u201cMe cambi\u00f3 la vida ir al espacio\u201d, admite Jos\u00e9 Hern\u00e1ndez, quien en dos ocasiones ha tenido la oportunidad de ver al planeta Tierra desde el espacio. \u201cDoce veces lo intent\u00e9 y lo logr\u00e9. Ver la Tierra desde otra perspectiva tiene un impacto profundo en ti\u201d, comparte quien, cuando era ni\u00f1o, ayudaba a su padre en las cosechas, viajando desde el sur de California hasta Michoac\u00e1n cada mes de marzo. Y fue uno de sos d\u00edas durante su dura infancia cuando fue testigo del suceso que lo llevar\u00eda a fijar su meta en la vida. \u201cMe encontraba limpiando con azad\u00f3n una fila de remolacha azucarera en un campo de cultivo cerca de Stockton, California y escuch\u00e9 en la radio de transistores que Franklin Chang-D\u00edaz hab\u00eda sido seleccionado como astronauta\u2026 y all\u00ed fue cuando me naci\u00f3 el sue\u00f1o de querer ser astronauta\u201d, narra y, como cualquier ni\u00f1o que acaba de encontrar su meta en la vida, corri\u00f3 a cont\u00e1rselo a su padre, quien, lejos de hacerle ver lo imposible que aquello sonaba, \u201cme dio una receta muy simple para llegar a cumplirla (su meta)\u201d. \u201cMe sent\u00f3 en la mesa de la cocina y me dijo que si quer\u00eda ser astronauta siguiera estos pasos: \u2018Define tu meta; reconoce qu\u00e9 tan lejos est\u00e1s de esa meta; crea una ruta o plan que te va a llevar a cumplir tu sue\u00f1o; ed\u00facate, pues no hay sustituto para llegar a la meta sin una buena educaci\u00f3n; y finalmente ten ganas y perseverancia&#8216;\u201d, el peque\u00f1o Jos\u00e9 escuch\u00f3 con atenci\u00f3n y sigui\u00f3 cada uno de esos pasos; tras a\u00f1os de perseverancia y esfuerzo, pudo tocar las estrellas. \u201cYo vine de una familia muy pobre, muy humilde, de familia inmigrante campesina y este pa\u00eds me dio la oportunidad de estudiar y perseguir mis sue\u00f1os como astronauta\u201d, dice orgulloso Jos\u00e9 Hern\u00e1ndez, quien actualmente se encuentra promoviendo un libro que decidi\u00f3 escribir dise\u00f1ado para ni\u00f1os, titulado El ni\u00f1o que toc\u00f3 las estrellas, el cual es su segunda obra, siendo la primera Cosechador de estrellas. &nbsp; Fuente: NASA, Exc\u00e9lsior, Radio F\u00f3rmula<\/p>","protected":false},"author":13,"featured_media":3406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-12347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orgullo-latino"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jos\u00e9 Hern\u00e1ndez: &#039;El ni\u00f1o que toc\u00f3 las estrellas&#039;<\/title>\n<meta name=\"description\" content=\"Jos\u00e9 Hern\u00e1ndez: &#039;El ni\u00f1o que toc\u00f3 las estrellas&#039;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Hern\u00e1ndez: &#039;El ni\u00f1o que toc\u00f3 las estrellas&#039;\" \/>\n<meta property=\"og:description\" content=\"Jos\u00e9 Hern\u00e1ndez: &#039;El ni\u00f1o que toc\u00f3 las estrellas&#039;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-16T22:55:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T20:06:02+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Jos\u00e9 Hern\u00e1ndez: &#8216;El ni\u00f1o que toc\u00f3 las estrellas&#8217;\",\"datePublished\":\"2016-03-16T22:55:55+00:00\",\"dateModified\":\"2025-10-29T20:06:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/\"},\"wordCount\":495,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Orgullo Latino\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/\",\"name\":\"Jos\u00e9 Hern\u00e1ndez: 'El ni\u00f1o que toc\u00f3 las estrellas'\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-03-16T22:55:55+00:00\",\"dateModified\":\"2025-10-29T20:06:02+00:00\",\"description\":\"Jos\u00e9 Hern\u00e1ndez: 'El ni\u00f1o que toc\u00f3 las estrellas'\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/jose-hernandez-el-nino-que-toco-las-estrellas\\\/orgullo-latino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orgullo Latino\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/orgullo-latino\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jos\u00e9 Hern\u00e1ndez: &#8216;El ni\u00f1o que toc\u00f3 las estrellas&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Hern\u00e1ndez: 'El ni\u00f1o que toc\u00f3 las estrellas'","description":"Jos\u00e9 Hern\u00e1ndez: 'El ni\u00f1o que toc\u00f3 las estrellas'","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/","og_locale":"en_US","og_type":"article","og_title":"Jos\u00e9 Hern\u00e1ndez: 'El ni\u00f1o que toc\u00f3 las estrellas'","og_description":"Jos\u00e9 Hern\u00e1ndez: 'El ni\u00f1o que toc\u00f3 las estrellas'","og_url":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-03-16T22:55:55+00:00","article_modified_time":"2025-10-29T20:06:02+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Jos\u00e9 Hern\u00e1ndez: &#8216;El ni\u00f1o que toc\u00f3 las estrellas&#8217;","datePublished":"2016-03-16T22:55:55+00:00","dateModified":"2025-10-29T20:06:02+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/"},"wordCount":495,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/#primaryimage"},"thumbnailUrl":"","articleSection":["Orgullo Latino"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/","url":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/","name":"Jos\u00e9 Hern\u00e1ndez: 'El ni\u00f1o que toc\u00f3 las estrellas'","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-03-16T22:55:55+00:00","dateModified":"2025-10-29T20:06:02+00:00","description":"Jos\u00e9 Hern\u00e1ndez: 'El ni\u00f1o que toc\u00f3 las estrellas'","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/jose-hernandez-el-nino-que-toco-las-estrellas\/orgullo-latino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Orgullo Latino","item":"https:\/\/accesolatino.org\/category\/orgullo-latino\/"},{"@type":"ListItem","position":3,"name":"Jos\u00e9 Hern\u00e1ndez: &#8216;El ni\u00f1o que toc\u00f3 las estrellas&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12347"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12347\/revisions"}],"predecessor-version":[{"id":67792,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12347\/revisions\/67792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}