{"id":12316,"date":"2016-02-23T11:55:57","date_gmt":"2016-02-23T17:55:57","guid":{"rendered":"https:\/\/accesolatino.org\/?p=3195"},"modified":"2025-10-29T14:20:43","modified_gmt":"2025-10-29T20:20:43","slug":"abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/","title":{"rendered":"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA"},"content":{"rendered":"<p>Desde que entr\u00f3 en vigor, en 2012, la <strong>Acci\u00f3n Diferida para los Llegados en la Infancia<\/strong> (<strong>DACA<\/strong>, por sus siglas en ingl\u00e9s), ha sido una salvaci\u00f3n para cerca de 700 mil inmigrantes indocumentados, quienes han podido ingresar a universidades y obtener empleo; sin embargo, seg\u00fan cifras oficiales se estima que<strong> hay cerca de 800 mil indocumentados en Estados Unidos que califican para obtenerlo y no lo han hecho<\/strong>, de ellos, aproximadamente <strong>100 mil viven en Los Angeles<\/strong>.<\/p>\n<p>Es por ello que desde el 1 de enero de 2016, la <strong>Barra de Abogados del condado de Los Angeles<\/strong> (<strong>LACBA<\/strong>, por sus siglas en ingl\u00e9s) cre\u00f3 el <strong>Proyecto de Asistencia Legal Migratoria<\/strong>, el cual es operado por 85 abogados especializados en inmigraci\u00f3n voluntarios que se han sumado a la lista de organizaciones que <strong>ofrecen ayuda legal gratuita a los j\u00f3venes indocumentados que califican para DACA<\/strong>.<\/p>\n<p>Mary Mucha, directora de abogados de <strong>LACBA<\/strong>, explic\u00f3 que este proyecto, que estar\u00e1 vigente hasta el 30 de junio de 2017, <strong>gu\u00eda y ayuda a los inmigrantes indocumentados con sus solicitudes y renovaciones de DACA<\/strong>. Asimismo, les resuelve dudas sobre permisos para viajar al extranjero, oportunidades laborales y peticiones de familiares.<\/p>\n<p>Mary comenta que \u201chay miles de \u2018so\u00f1adores\u2019 que necesitan renovar su aplicaci\u00f3n y aqu\u00ed pueden recibir asesor\u00eda gratuita en sus casos de inmigraci\u00f3n y de otros problemas migratorios que pudieran tener en sus familias\u201d.<\/p>\n<p>\u201cVengan a hablar con experimentados abogados de inmigraci\u00f3n, no vayan con notarios o con personas que no son abogados\u201d, es el mensaje de Mary para la comunidad indocumentada. \u201cHay mucha desinformaci\u00f3n, por eso queremos garantizar que los \u2018so\u00f1adores\u2019 entiendan sus derechos bajo <strong>DACA<\/strong>\u201d, agreg\u00f3.<\/p>\n<p>Para beneficiarse de este servicio gratuito no es necesario hacer una cita. Los interesados pueden acudir de lunes a viernes, de 8:00 am a 12 pm, y de 1:00 pm a 3:00 pm a la oficina de <strong>LACBA<\/strong>, ubicada en 300 N. Los Angeles Street, cuarto 3107 (tercer piso), 90012.<\/p>\n<p>Para m\u00e1s informaci\u00f3n puedes llamar al tel\u00e9fono (213) 485-1873.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>La Opini\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Desde que entr\u00f3 en vigor, en 2012, la Acci\u00f3n Diferida para los Llegados en la Infancia (DACA, por sus siglas en ingl\u00e9s), ha sido una salvaci\u00f3n para cerca de 700 mil inmigrantes indocumentados, quienes han podido ingresar a universidades y obtener empleo; sin embargo, seg\u00fan cifras oficiales se estima que hay cerca de 800 mil indocumentados en Estados Unidos que califican para obtenerlo y no lo han hecho, de ellos, aproximadamente 100 mil viven en Los Angeles. Es por ello que desde el 1 de enero de 2016, la Barra de Abogados del condado de Los Angeles (LACBA, por sus siglas en ingl\u00e9s) cre\u00f3 el Proyecto de Asistencia Legal Migratoria, el cual es operado por 85 abogados especializados en inmigraci\u00f3n voluntarios que se han sumado a la lista de organizaciones que ofrecen ayuda legal gratuita a los j\u00f3venes indocumentados que califican para DACA. Mary Mucha, directora de abogados de LACBA, explic\u00f3 que este proyecto, que estar\u00e1 vigente hasta el 30 de junio de 2017, gu\u00eda y ayuda a los inmigrantes indocumentados con sus solicitudes y renovaciones de DACA. Asimismo, les resuelve dudas sobre permisos para viajar al extranjero, oportunidades laborales y peticiones de familiares. Mary comenta que \u201chay miles de \u2018so\u00f1adores\u2019 que necesitan renovar su aplicaci\u00f3n y aqu\u00ed pueden recibir asesor\u00eda gratuita en sus casos de inmigraci\u00f3n y de otros problemas migratorios que pudieran tener en sus familias\u201d. \u201cVengan a hablar con experimentados abogados de inmigraci\u00f3n, no vayan con notarios o con personas que no son abogados\u201d, es el mensaje de Mary para la comunidad indocumentada. \u201cHay mucha desinformaci\u00f3n, por eso queremos garantizar que los \u2018so\u00f1adores\u2019 entiendan sus derechos bajo DACA\u201d, agreg\u00f3. Para beneficiarse de este servicio gratuito no es necesario hacer una cita. Los interesados pueden acudir de lunes a viernes, de 8:00 am a 12 pm, y de 1:00 pm a 3:00 pm a la oficina de LACBA, ubicada en 300 N. Los Angeles Street, cuarto 3107 (tercer piso), 90012. Para m\u00e1s informaci\u00f3n puedes llamar al tel\u00e9fono (213) 485-1873. &nbsp; Fuente: La Opini\u00f3n<\/p>","protected":false},"author":1,"featured_media":3197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA<\/title>\n<meta name=\"description\" content=\"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA\" \/>\n<meta property=\"og:description\" content=\"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-23T17:55:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T20:20:43+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\"},\"headline\":\"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA\",\"datePublished\":\"2016-02-23T17:55:57+00:00\",\"dateModified\":\"2025-10-29T20:20:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/\"},\"wordCount\":347,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/\",\"name\":\"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-02-23T17:55:57+00:00\",\"dateModified\":\"2025-10-29T20:20:43+00:00\",\"description\":\"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA","description":"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA","og_description":"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA","og_url":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-02-23T17:55:57+00:00","article_modified_time":"2025-10-29T20:20:43+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/"},"author":{"name":"admin","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d"},"headline":"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA","datePublished":"2016-02-23T17:55:57+00:00","dateModified":"2025-10-29T20:20:43+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/"},"wordCount":347,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/","url":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/","name":"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-02-23T17:55:57+00:00","dateModified":"2025-10-29T20:20:43+00:00","description":"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/abogados-de-los-angeles-ofrecen-ayuda-gratuita-para-tramitar-daca\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Abogados de Los Angeles ofrecen ayuda gratuita para tramitar DACA"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d","name":"admin"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12316"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12316\/revisions"}],"predecessor-version":[{"id":67831,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12316\/revisions\/67831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}