{"id":12282,"date":"2016-01-20T11:55:06","date_gmt":"2016-01-20T17:55:06","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2976"},"modified":"2025-10-29T18:02:59","modified_gmt":"2025-10-30T00:02:59","slug":"otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/","title":{"rendered":"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o"},"content":{"rendered":"<p>Un total de <strong>m\u00e1s de 600 mil licencias han sido otorgadas a indocumentados en California en poco m\u00e1s de un a\u00f1o<\/strong>, desde que el 2 de enero de 2015 entrara en vigor la ley AB60 en este estado.<\/p>\n<p>Tras cumplirse el primer a\u00f1o de la aplicaci\u00f3n de esta ley, que permite al <strong>Departamento de Veh\u00edculos Motorizados<\/strong> (<strong>DMV<\/strong>, por sus siglas en ingl\u00e9s) otorgar licencias de conducir a indocumentados en California, <strong>m\u00e1s de 600 mil permisos han sido aprobados<\/strong>, siendo el n\u00famero m\u00e1s grande de licencias otorgadas en cualquier estado del pa\u00eds norteamericano.<\/p>\n<p>Seg\u00fan cifras recopiladas por <strong>DMV<\/strong>, hasta el 25 de diciembre de 2015 los usuarios del servicio realizaron m\u00e1s de 2 millones de visitas a las 174 oficinas y cuatro centros de procesamiento de la dependencia.<\/p>\n<p>Artemio Armenta, portavoz de <strong>DMV<\/strong>, dijo que esta \u201ces una cifra muy significativa porque llegamos al fin de a\u00f1o y sobrepasamos las expectativas. Nunca en la historia el <strong>DMV<\/strong> hab\u00eda implementado un programa de este tama\u00f1o\u201d, y resalt\u00f3 que hubo \u201caproximadamente 2,1 millones de ex\u00e1menes, ya sea de conocimiento o de manejo, administrados durante el a\u00f1o\u201d.<\/p>\n<p><strong>DMV<\/strong> calcula recibir cerca de 1.5 millones de solicitudes en los tres primeros a\u00f1os de aplicaci\u00f3n de la ley, sin embargo apenas en los primeros seis meses ya hab\u00edan recibido lo calculado para todo el primer a\u00f1o. Con el ritmo actual de solicitudes y el n\u00famero total de licencias otorgadas en el primer a\u00f1o, se espera que entre 2016 y 2017 se complete el c\u00e1lculo inicial de 1.5 millones de licencias de conducir.<\/p>\n<p>Un an\u00e1lisis del Instituto de Pol\u00edtica P\u00fablica de California calcul\u00f3 que <strong>en California hay m\u00e1s de 1.4 millones de indocumentados que pueden solicitar la licencia de conducir<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>EFE<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Un total de m\u00e1s de 600 mil licencias han sido otorgadas a indocumentados en California en poco m\u00e1s de un a\u00f1o, desde que el 2 de enero de 2015 entrara en vigor la ley AB60 en este estado. Tras cumplirse el primer a\u00f1o de la aplicaci\u00f3n de esta ley, que permite al Departamento de Veh\u00edculos Motorizados (DMV, por sus siglas en ingl\u00e9s) otorgar licencias de conducir a indocumentados en California, m\u00e1s de 600 mil permisos han sido aprobados, siendo el n\u00famero m\u00e1s grande de licencias otorgadas en cualquier estado del pa\u00eds norteamericano. Seg\u00fan cifras recopiladas por DMV, hasta el 25 de diciembre de 2015 los usuarios del servicio realizaron m\u00e1s de 2 millones de visitas a las 174 oficinas y cuatro centros de procesamiento de la dependencia. Artemio Armenta, portavoz de DMV, dijo que esta \u201ces una cifra muy significativa porque llegamos al fin de a\u00f1o y sobrepasamos las expectativas. Nunca en la historia el DMV hab\u00eda implementado un programa de este tama\u00f1o\u201d, y resalt\u00f3 que hubo \u201caproximadamente 2,1 millones de ex\u00e1menes, ya sea de conocimiento o de manejo, administrados durante el a\u00f1o\u201d. DMV calcula recibir cerca de 1.5 millones de solicitudes en los tres primeros a\u00f1os de aplicaci\u00f3n de la ley, sin embargo apenas en los primeros seis meses ya hab\u00edan recibido lo calculado para todo el primer a\u00f1o. Con el ritmo actual de solicitudes y el n\u00famero total de licencias otorgadas en el primer a\u00f1o, se espera que entre 2016 y 2017 se complete el c\u00e1lculo inicial de 1.5 millones de licencias de conducir. Un an\u00e1lisis del Instituto de Pol\u00edtica P\u00fablica de California calcul\u00f3 que en California hay m\u00e1s de 1.4 millones de indocumentados que pueden solicitar la licencia de conducir. &nbsp; Fuente: EFE<\/p>","protected":false},"author":1,"featured_media":2977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o<\/title>\n<meta name=\"description\" content=\"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o\" \/>\n<meta property=\"og:description\" content=\"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-20T17:55:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T00:02:59+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\"},\"headline\":\"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o\",\"datePublished\":\"2016-01-20T17:55:06+00:00\",\"dateModified\":\"2025-10-30T00:02:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/\",\"name\":\"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-01-20T17:55:06+00:00\",\"dateModified\":\"2025-10-30T00:02:59+00:00\",\"description\":\"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o","description":"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o","og_description":"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o","og_url":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-01-20T17:55:06+00:00","article_modified_time":"2025-10-30T00:02:59+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/"},"author":{"name":"admin","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d"},"headline":"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o","datePublished":"2016-01-20T17:55:06+00:00","dateModified":"2025-10-30T00:02:59+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/","url":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/","name":"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-01-20T17:55:06+00:00","dateModified":"2025-10-30T00:02:59+00:00","description":"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/otorgamiento-de-licencias-a-indocumentados-en-california-cumple-un-ano\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Otorgamiento de licencias a indocumentados en California cumple un a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d","name":"admin"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12282"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12282\/revisions"}],"predecessor-version":[{"id":67907,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12282\/revisions\/67907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}