{"id":12264,"date":"2016-01-06T11:55:42","date_gmt":"2016-01-06T17:55:42","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2860"},"modified":"2025-10-29T18:06:27","modified_gmt":"2025-10-30T00:06:27","slug":"cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/","title":{"rendered":"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil"},"content":{"rendered":"<p>Una fuente oficial inform\u00f3 que las autoridades migratorias de Estados Unidos y M\u00e9xico deportaron en todo 2015 a cerca de <strong>70 mil inmigrantes hondure\u00f1os<\/strong>, lo que signific\u00f3 11 mil deportados menos que los registrados durante el a\u00f1o 2014.<\/p>\n<p>Un informe del Centro de Atenci\u00f3n al Migrante Retornado (CAMR, privado) se\u00f1al\u00f3 que los \u00faltimos 165 ciudadanos hondure\u00f1os deportados de Estados Unidos este a\u00f1o llegaron al pa\u00eds centroamericano el pasado 30 de diciembre en dos vuelos a San Pedro Sula, norte del pa\u00eds hondure\u00f1o, detall\u00f3 la fuente.<\/p>\n<p>El n\u00famero de inmigrantes hondure\u00f1os deportados en 2015 por las autoridades migratorias de Estados Unidos sumaron un total de <strong>19 mil 336<\/strong>, cifra que <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/disminuye-numero-de-inmigrantes-hondurenos-deportados-en-2015\/\" target=\"_blank\" rel=\"noopener\">se redujo cerca de un 40%<\/a><\/span> con respecto a los registros de 2014, sin embargo, el n\u00famero de inmigrantes hondure\u00f1os deportados por autoridades en M\u00e9xico se duplic\u00f3, registrando cerca de <strong>50 mil por v\u00eda terrestre<\/strong>, indic\u00f3 el CAMR.<\/p>\n<p>Por su parte, las autoridades de Tegucigalpa, capital hondure\u00f1a, calculan que <strong>en Estados Unidos viven 1.2 millones de inmigrantes hondure\u00f1os<\/strong>, entre residentes legales e indocumentados, que este a\u00f1o enviaron remesas familiares que superaron los 3 mil 500 millones de d\u00f3lares.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>EFE<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Una fuente oficial inform\u00f3 que las autoridades migratorias de Estados Unidos y M\u00e9xico deportaron en todo 2015 a cerca de 70 mil inmigrantes hondure\u00f1os, lo que signific\u00f3 11 mil deportados menos que los registrados durante el a\u00f1o 2014. Un informe del Centro de Atenci\u00f3n al Migrante Retornado (CAMR, privado) se\u00f1al\u00f3 que los \u00faltimos 165 ciudadanos hondure\u00f1os deportados de Estados Unidos este a\u00f1o llegaron al pa\u00eds centroamericano el pasado 30 de diciembre en dos vuelos a San Pedro Sula, norte del pa\u00eds hondure\u00f1o, detall\u00f3 la fuente. El n\u00famero de inmigrantes hondure\u00f1os deportados en 2015 por las autoridades migratorias de Estados Unidos sumaron un total de 19 mil 336, cifra que se redujo cerca de un 40% con respecto a los registros de 2014, sin embargo, el n\u00famero de inmigrantes hondure\u00f1os deportados por autoridades en M\u00e9xico se duplic\u00f3, registrando cerca de 50 mil por v\u00eda terrestre, indic\u00f3 el CAMR. Por su parte, las autoridades de Tegucigalpa, capital hondure\u00f1a, calculan que en Estados Unidos viven 1.2 millones de inmigrantes hondure\u00f1os, entre residentes legales e indocumentados, que este a\u00f1o enviaron remesas familiares que superaron los 3 mil 500 millones de d\u00f3lares. &nbsp; Fuente: EFE<\/p>","protected":false},"author":13,"featured_media":2862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inmigrantes hondure\u00f1os deportados en 2015: 70 mil<\/title>\n<meta name=\"description\" content=\"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil\" \/>\n<meta property=\"og:description\" content=\"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-06T17:55:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T00:06:27+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil\",\"datePublished\":\"2016-01-06T17:55:42+00:00\",\"dateModified\":\"2025-10-30T00:06:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/\"},\"wordCount\":201,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/\",\"name\":\"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-01-06T17:55:42+00:00\",\"dateModified\":\"2025-10-30T00:06:27+00:00\",\"description\":\"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil","description":"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil","og_description":"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil","og_url":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-01-06T17:55:42+00:00","article_modified_time":"2025-10-30T00:06:27+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil","datePublished":"2016-01-06T17:55:42+00:00","dateModified":"2025-10-30T00:06:27+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/"},"wordCount":201,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/","url":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/","name":"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-01-06T17:55:42+00:00","dateModified":"2025-10-30T00:06:27+00:00","description":"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/cerca-de-70-mil-inmigrantes-hondurenos-fueron-deportados-en-2015\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Inmigrantes hondure\u00f1os deportados en 2015: 70 mil"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12264"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12264\/revisions"}],"predecessor-version":[{"id":67924,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12264\/revisions\/67924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}