{"id":12243,"date":"2015-12-16T11:55:34","date_gmt":"2015-12-16T17:55:34","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2718"},"modified":"2025-10-29T18:27:02","modified_gmt":"2025-10-30T00:27:02","slug":"indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/","title":{"rendered":"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias"},"content":{"rendered":"<p>Desde el pasado 15 de diciembre, numerosas familias de inmigrantes indocumentados a lo largo de Nuevo M\u00e9xico se han unido para participar en una serie de vigilias pidiendo que se mantengan las licencias de conducir para su comunidad en dicho estado.<\/p>\n<p>Las vigilias se llevar\u00e1n a cabo en 10 diferentes condados de Nuevo M\u00e9xico, comenzando en la ciudad de Dexter y finalizando el pr\u00f3ximo lunes 21 de diciembre en Los Lunas.<\/p>\n<p>Los inmigrantes indocumentados piden a los legisladores estatales que no dejen pasar durante la pr\u00f3xima sesi\u00f3n legislativa (que inicia en enero) una legislaci\u00f3n que quita las licencias a los inmigrantes indocumentados, en nombre de la legislaci\u00f3n federal conocida como <strong>Real ID Act<\/strong>.<\/p>\n<p>Marcela D\u00edaz, directora del grupo Somos Un Pueblo Unido con base en Santa Fe, explica que &#8220;el <strong>Real ID<\/strong> no obliga a los estados a marcar a los inmigrantes con un permiso de conducir discriminatorio tal y como algunos quieren que la gente viva&#8221;.<\/p>\n<p>A partir de enero de 2016 se cumple una nueva etapa de la legislaci\u00f3n federal del <strong>Real ID<\/strong>, aprobada en el 2005, la cual obliga a los estados emitir licencias de conducir a indocumentados que cumplan con varios requisitos de seguridad.<\/p>\n<p>Las licencias de conducir en Nuevo M\u00e9xico no cumplen con estos requerimientos federales, por lo que corren el riesgo de que a partir del pr\u00f3ximo a\u00f1o pierdan su valor como una forma de identificaci\u00f3n.<\/p>\n<p>Para cumplir con la legislaci\u00f3n federal, Nuevo M\u00e9xico ha indicado que presentar\u00e1 una propuesta para cambiar la ley en ese estado, otorgando &#8220;permisos&#8221; de conducir a los inmigrantes indocumentados y no licencias.<\/p>\n<p>Seg\u00fan D\u00edaz &#8220;un permiso de trabajo no debe estigmatizar a las personas basadas en su grupo \u00e9tnico o lugar de origen, es innecesario&#8221;.<\/p>\n<p>Fuente: <em>EFE<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Desde el pasado 15 de diciembre, numerosas familias de inmigrantes indocumentados a lo largo de Nuevo M\u00e9xico se han unido para participar en una serie de vigilias pidiendo que se mantengan las licencias de conducir para su comunidad en dicho estado. Las vigilias se llevar\u00e1n a cabo en 10 diferentes condados de Nuevo M\u00e9xico, comenzando en la ciudad de Dexter y finalizando el pr\u00f3ximo lunes 21 de diciembre en Los Lunas. Los inmigrantes indocumentados piden a los legisladores estatales que no dejen pasar durante la pr\u00f3xima sesi\u00f3n legislativa (que inicia en enero) una legislaci\u00f3n que quita las licencias a los inmigrantes indocumentados, en nombre de la legislaci\u00f3n federal conocida como Real ID Act. Marcela D\u00edaz, directora del grupo Somos Un Pueblo Unido con base en Santa Fe, explica que &#8220;el Real ID no obliga a los estados a marcar a los inmigrantes con un permiso de conducir discriminatorio tal y como algunos quieren que la gente viva&#8221;. A partir de enero de 2016 se cumple una nueva etapa de la legislaci\u00f3n federal del Real ID, aprobada en el 2005, la cual obliga a los estados emitir licencias de conducir a indocumentados que cumplan con varios requisitos de seguridad. Las licencias de conducir en Nuevo M\u00e9xico no cumplen con estos requerimientos federales, por lo que corren el riesgo de que a partir del pr\u00f3ximo a\u00f1o pierdan su valor como una forma de identificaci\u00f3n. Para cumplir con la legislaci\u00f3n federal, Nuevo M\u00e9xico ha indicado que presentar\u00e1 una propuesta para cambiar la ley en ese estado, otorgando &#8220;permisos&#8221; de conducir a los inmigrantes indocumentados y no licencias. Seg\u00fan D\u00edaz &#8220;un permiso de trabajo no debe estigmatizar a las personas basadas en su grupo \u00e9tnico o lugar de origen, es innecesario&#8221;. Fuente: EFE<\/p>","protected":false},"author":13,"featured_media":2719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Indocumentados de Nuevo M\u00e9xico buscan mantener licencias<\/title>\n<meta name=\"description\" content=\"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias\" \/>\n<meta property=\"og:description\" content=\"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-16T17:55:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T00:27:02+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias\",\"datePublished\":\"2015-12-16T17:55:34+00:00\",\"dateModified\":\"2025-10-30T00:27:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/\"},\"wordCount\":310,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/\",\"name\":\"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-12-16T17:55:34+00:00\",\"dateModified\":\"2025-10-30T00:27:02+00:00\",\"description\":\"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias","description":"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias","og_description":"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias","og_url":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-12-16T17:55:34+00:00","article_modified_time":"2025-10-30T00:27:02+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias","datePublished":"2015-12-16T17:55:34+00:00","dateModified":"2025-10-30T00:27:02+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/"},"wordCount":310,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/","url":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/","name":"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-12-16T17:55:34+00:00","dateModified":"2025-10-30T00:27:02+00:00","description":"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/indocumentados-de-nuevo-mexico-buscan-que-se-mantengan-licencias-de-conducir\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Indocumentados de Nuevo M\u00e9xico buscan mantener licencias"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12243"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12243\/revisions"}],"predecessor-version":[{"id":67967,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12243\/revisions\/67967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}