{"id":12195,"date":"2015-11-11T11:55:51","date_gmt":"2015-11-11T17:55:51","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2484"},"modified":"2025-10-29T19:04:11","modified_gmt":"2025-10-30T01:04:11","slug":"pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/","title":{"rendered":"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU"},"content":{"rendered":"<p><em>Hispanic Affairs Project<\/em> (HAP), organizaci\u00f3n de activistas latinos del estado de Colorado, ha presentado demandas para defender los derechos de los pastores de ovejas, trabajo que realizan inmigrantes latinos en malas condiciones, se\u00f1ala la organizaci\u00f3n.<\/p>\n<p>Al menos en nueve estados del pa\u00eds, expone HAP, <strong>cerca de 1,600 trabajadores inmigrantes con visas H2-A hacen uno de las labores m\u00e1s duras y peor pagadas en los Estados Unidos: pastor de oveja<\/strong>.<\/p>\n<p>La organizaci\u00f3n argumenta que la mayor\u00eda de los pastores<strong> trabaja las 24 horas y carecen de d\u00edas libres<\/strong>, adem\u00e1s que no se les permite salir del rancho donde laboran ni tener contacto con el mundo exterior. \u201cEs un trabajo muy solitario y en la industria hay un orgullo de mantener la tradici\u00f3n de hacerlo como se hac\u00eda hace m\u00e1s de 100 a\u00f1os\u201d, comenta Ricardo P\u00e9rez, director ejecutivo de HAP en Colorado.<\/p>\n<p><strong>La mayor\u00eda de los inmigrantes que trabajan como pastores de ovejas provienen de Per\u00fa, Bolivia y M\u00e9xico<\/strong>, incluidos algunos de Nepal, y, de acuerdo con HAP, viven aislados con sus reba\u00f1os, dependiendo para todo de sus patrones sin poder cambiar de trabajo, pues eso cancelar\u00eda su visa.<\/p>\n<p>Seg\u00fan P\u00e9rez, los inmigrantes se ven condicionados por sus patrones, pues \u201clos recogen del aeropuerto, los llevan al rancho y les proh\u00edben salir, con pretexto de que pueden ser reportados y deportados\u201d. La demanda federal presentada por HAP alega que el <strong>Departamento del Trabajo<\/strong> ha fallado en su labor de regular la industria y de garantizar que no hay da\u00f1o al trabajador.<\/p>\n<p>Por su parte, el <strong>Departamento del Trabajo<\/strong> expres\u00f3 al respecto que \u201cla naturaleza de estos oficios, disponibilidad cont\u00ednua 24\/7 en lugares remotos y la escasez de trabajadores estadounidenses en los mismos, han hecho dif\u00edcil el establecimiento de un salario m\u00ednimo adecuado, resultando en estancamiento de los salarios durante casi 20 a\u00f1os\u201d.<\/p>\n<p>Adem\u00e1s del aumento al salario de los pastores de ovejas, la demanda tambi\u00e9n ha provocado que se incluyan requisitos m\u00ednimos de vivienda para los inmigrantes (calefacci\u00f3n), y la obligaci\u00f3n de los patrones de proporcionar comida gratis y un m\u00ednimo de 4.5 galones de agua potable diarios a sus trabajadores.<\/p>\n<p>Sin embargo, la industria de la lana y la carne de cordero se ha resistido a estos cambios y ha dicho que, de llevarlos a cabo, terminar\u00e1 por cerrar muchos ranchos, provocando la p\u00e9rdida de trabajos; por lo que han pedido que se anulen las nuevas reglas.<\/p>\n<p>Fuente: <em>El Diario NY<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Hispanic Affairs Project (HAP), organizaci\u00f3n de activistas latinos del estado de Colorado, ha presentado demandas para defender los derechos de los pastores de ovejas, trabajo que realizan inmigrantes latinos en malas condiciones, se\u00f1ala la organizaci\u00f3n. Al menos en nueve estados del pa\u00eds, expone HAP, cerca de 1,600 trabajadores inmigrantes con visas H2-A hacen uno de las labores m\u00e1s duras y peor pagadas en los Estados Unidos: pastor de oveja. La organizaci\u00f3n argumenta que la mayor\u00eda de los pastores trabaja las 24 horas y carecen de d\u00edas libres, adem\u00e1s que no se les permite salir del rancho donde laboran ni tener contacto con el mundo exterior. \u201cEs un trabajo muy solitario y en la industria hay un orgullo de mantener la tradici\u00f3n de hacerlo como se hac\u00eda hace m\u00e1s de 100 a\u00f1os\u201d, comenta Ricardo P\u00e9rez, director ejecutivo de HAP en Colorado. La mayor\u00eda de los inmigrantes que trabajan como pastores de ovejas provienen de Per\u00fa, Bolivia y M\u00e9xico, incluidos algunos de Nepal, y, de acuerdo con HAP, viven aislados con sus reba\u00f1os, dependiendo para todo de sus patrones sin poder cambiar de trabajo, pues eso cancelar\u00eda su visa. Seg\u00fan P\u00e9rez, los inmigrantes se ven condicionados por sus patrones, pues \u201clos recogen del aeropuerto, los llevan al rancho y les proh\u00edben salir, con pretexto de que pueden ser reportados y deportados\u201d. La demanda federal presentada por HAP alega que el Departamento del Trabajo ha fallado en su labor de regular la industria y de garantizar que no hay da\u00f1o al trabajador. Por su parte, el Departamento del Trabajo expres\u00f3 al respecto que \u201cla naturaleza de estos oficios, disponibilidad cont\u00ednua 24\/7 en lugares remotos y la escasez de trabajadores estadounidenses en los mismos, han hecho dif\u00edcil el establecimiento de un salario m\u00ednimo adecuado, resultando en estancamiento de los salarios durante casi 20 a\u00f1os\u201d. Adem\u00e1s del aumento al salario de los pastores de ovejas, la demanda tambi\u00e9n ha provocado que se incluyan requisitos m\u00ednimos de vivienda para los inmigrantes (calefacci\u00f3n), y la obligaci\u00f3n de los patrones de proporcionar comida gratis y un m\u00ednimo de 4.5 galones de agua potable diarios a sus trabajadores. Sin embargo, la industria de la lana y la carne de cordero se ha resistido a estos cambios y ha dicho que, de llevarlos a cabo, terminar\u00e1 por cerrar muchos ranchos, provocando la p\u00e9rdida de trabajos; por lo que han pedido que se anulen las nuevas reglas. Fuente: El Diario NY<\/p>","protected":false},"author":13,"featured_media":2485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-12195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empleo"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pastor de ovejas, un trabajo duro para inmigrantes en EE UU<\/title>\n<meta name=\"description\" content=\"Cerca de 1,600 trabajadores inmigrantes latinos con visas H2-A hacen uno de las labores m\u00e1s duras y peor pagadas en los Estados Unidos: pastor de oveja.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU\" \/>\n<meta property=\"og:description\" content=\"Cerca de 1,600 trabajadores inmigrantes latinos con visas H2-A hacen uno de las labores m\u00e1s duras y peor pagadas en los Estados Unidos: pastor de oveja.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-11T17:55:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:04:11+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU\",\"datePublished\":\"2015-11-11T17:55:51+00:00\",\"dateModified\":\"2025-10-30T01:04:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Empleo\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/\",\"name\":\"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-11-11T17:55:51+00:00\",\"dateModified\":\"2025-10-30T01:04:11+00:00\",\"description\":\"Cerca de 1,600 trabajadores inmigrantes latinos con visas H2-A hacen uno de las labores m\u00e1s duras y peor pagadas en los Estados Unidos: pastor de oveja.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\\\/empleo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empleo\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/empleo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU","description":"Cerca de 1,600 trabajadores inmigrantes latinos con visas H2-A hacen uno de las labores m\u00e1s duras y peor pagadas en los Estados Unidos: pastor de oveja.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/","og_locale":"en_US","og_type":"article","og_title":"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU","og_description":"Cerca de 1,600 trabajadores inmigrantes latinos con visas H2-A hacen uno de las labores m\u00e1s duras y peor pagadas en los Estados Unidos: pastor de oveja.","og_url":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-11-11T17:55:51+00:00","article_modified_time":"2025-10-30T01:04:11+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU","datePublished":"2015-11-11T17:55:51+00:00","dateModified":"2025-10-30T01:04:11+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/#primaryimage"},"thumbnailUrl":"","articleSection":["Empleo"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/","url":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/","name":"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-11-11T17:55:51+00:00","dateModified":"2025-10-30T01:04:11+00:00","description":"Cerca de 1,600 trabajadores inmigrantes latinos con visas H2-A hacen uno de las labores m\u00e1s duras y peor pagadas en los Estados Unidos: pastor de oveja.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/pastor-de-ovejas-un-trabajo-duro-para-inmigrantes-en-ee-uu\/empleo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Empleo","item":"https:\/\/accesolatino.org\/en\/category\/empleo\/"},{"@type":"ListItem","position":3,"name":"Pastor de ovejas, un trabajo duro para inmigrantes en EE UU"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12195"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12195\/revisions"}],"predecessor-version":[{"id":68027,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12195\/revisions\/68027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}