{"id":12194,"date":"2015-11-10T11:55:03","date_gmt":"2015-11-10T17:55:03","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2477"},"modified":"2025-10-29T19:00:18","modified_gmt":"2025-10-30T01:00:18","slug":"visa-eb-5-peligra-en-el-estado-de-california","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/","title":{"rendered":"Visa EB-5 peligra en el estado de California"},"content":{"rendered":"<p>The <strong>Visa EB-5<\/strong> es un programa que otorga la nacionalidad estadounidense a inmigrantes que inviertan en alg\u00fan negocio de Estados Unidos y generen empleos, sin embargo un sector de California busca eliminarla del estado al considerarla injusta y susceptible al fraude.<\/p>\n<p>El programa de <strong>Visa EB-5<\/strong> permite a emprendedores inmigrantes hacer una inversi\u00f3n en un negocio de los Estados Unidos para obtener una <strong>Green Card holders<\/strong> y convertirse en un residente permanente. Los titulares de dicha visa pueden vivir y trabajar permanentemente en los Estados Unidos con sus c\u00f3nyuges e hijos solteros menores de 21 a\u00f1os.<\/p>\n<p>La cantidad de inversi\u00f3n requerida para obtener la visa depende del lugar donde est\u00e1 localizado el negocio que recibe la inversi\u00f3n, as\u00ed como del tipo de negocio. El capital invertido debe de ser de 1 mill\u00f3n de d\u00f3lares, aunque las inversiones en zonas econ\u00f3micamente deprimidas pueden ser de 500 mil d\u00f3lares. Adem\u00e1s, el negocio debe crear 10 puestos de trabajo por un m\u00ednimo de 2 a\u00f1os.<\/p>\n<p>De acuerdo con el sitio <a href=\"https:\/\/www.bisnow.com\/\" target=\"_blank\" rel=\"nofollow noopener\">Bisnow<\/a>, entre 2011 y 2014 la expedici\u00f3n de <strong>Visa EB-5<\/strong> aument\u00f3 en cerca de 6 mil y, agrega, en el \u00faltimo a\u00f1o, los desarrolladores estadounidenses han recaudado m\u00e1s de mil millones de d\u00f3lares, principalmente de inmigrantes asi\u00e1ticos.<\/p>\n<p>Seg\u00fan los grupos que buscan eliminar el programa en California argumentan que la <strong>Visa EB-5<\/strong> da una ventaja injusta para obtener la residencia permanente a los inmigrantes con mucho dinero, mientras que un estimado de 4.4 millones de inmigrantes son incapaces de hacer una inversi\u00f3n en el pa\u00eds.<\/p>\n<p>Asimismo, las contrapartes tambi\u00e9n cuestionan la legitimidad de las inversiones y exigen que existan medidas para detectar si se trata de un posible fraude. El Congreso determinar\u00e1 en diciembre de 2015 el futuro de la <strong>Visa EB-5<\/strong> en California.<\/p>\n<p>Fuente: <em>ViveUSA, Bisnow<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>La Visa EB-5 es un programa que otorga la nacionalidad estadounidense a inmigrantes que inviertan en alg\u00fan negocio de Estados Unidos y generen empleos, sin embargo un sector de California busca eliminarla del estado al considerarla injusta y susceptible al fraude. El programa de Visa EB-5 permite a emprendedores inmigrantes hacer una inversi\u00f3n en un negocio de los Estados Unidos para obtener una Green Card y convertirse en un residente permanente. Los titulares de dicha visa pueden vivir y trabajar permanentemente en los Estados Unidos con sus c\u00f3nyuges e hijos solteros menores de 21 a\u00f1os. La cantidad de inversi\u00f3n requerida para obtener la visa depende del lugar donde est\u00e1 localizado el negocio que recibe la inversi\u00f3n, as\u00ed como del tipo de negocio. El capital invertido debe de ser de 1 mill\u00f3n de d\u00f3lares, aunque las inversiones en zonas econ\u00f3micamente deprimidas pueden ser de 500 mil d\u00f3lares. Adem\u00e1s, el negocio debe crear 10 puestos de trabajo por un m\u00ednimo de 2 a\u00f1os. De acuerdo con el sitio Bisnow, entre 2011 y 2014 la expedici\u00f3n de Visa EB-5 aument\u00f3 en cerca de 6 mil y, agrega, en el \u00faltimo a\u00f1o, los desarrolladores estadounidenses han recaudado m\u00e1s de mil millones de d\u00f3lares, principalmente de inmigrantes asi\u00e1ticos. Seg\u00fan los grupos que buscan eliminar el programa en California argumentan que la Visa EB-5 da una ventaja injusta para obtener la residencia permanente a los inmigrantes con mucho dinero, mientras que un estimado de 4.4 millones de inmigrantes son incapaces de hacer una inversi\u00f3n en el pa\u00eds. Asimismo, las contrapartes tambi\u00e9n cuestionan la legitimidad de las inversiones y exigen que existan medidas para detectar si se trata de un posible fraude. El Congreso determinar\u00e1 en diciembre de 2015 el futuro de la Visa EB-5 en California. Fuente: ViveUSA, Bisnow<\/p>","protected":false},"author":13,"featured_media":2478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-12194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tramites"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visa EB-5 peligra en el estado de California<\/title>\n<meta name=\"description\" content=\"La Visa EB-5 otorga la nacionalidad estadounidense a inmigrantes que inviertan en alg\u00fan negocio de EE UU y generen empleos, sin embargo buscan eliminarla.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visa EB-5 peligra en el estado de California\" \/>\n<meta property=\"og:description\" content=\"La Visa EB-5 otorga la nacionalidad estadounidense a inmigrantes que inviertan en alg\u00fan negocio de EE UU y generen empleos, sin embargo buscan eliminarla.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-10T17:55:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:00:18+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Visa EB-5 peligra en el estado de California\",\"datePublished\":\"2015-11-10T17:55:03+00:00\",\"dateModified\":\"2025-10-30T01:00:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/\"},\"wordCount\":313,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Tr\u00e1mites\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/\",\"name\":\"Visa EB-5 peligra en el estado de California\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-11-10T17:55:03+00:00\",\"dateModified\":\"2025-10-30T01:00:18+00:00\",\"description\":\"La Visa EB-5 otorga la nacionalidad estadounidense a inmigrantes que inviertan en alg\u00fan negocio de EE UU y generen empleos, sin embargo buscan eliminarla.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/visa-eb-5-peligra-en-el-estado-de-california\\\/tramites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00e1mites\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/tramites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Visa EB-5 peligra en el estado de California\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visa EB-5 peligra en el estado de California","description":"La Visa EB-5 otorga la nacionalidad estadounidense a inmigrantes que inviertan en alg\u00fan negocio de EE UU y generen empleos, sin embargo buscan eliminarla.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/","og_locale":"en_US","og_type":"article","og_title":"Visa EB-5 peligra en el estado de California","og_description":"La Visa EB-5 otorga la nacionalidad estadounidense a inmigrantes que inviertan en alg\u00fan negocio de EE UU y generen empleos, sin embargo buscan eliminarla.","og_url":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-11-10T17:55:03+00:00","article_modified_time":"2025-10-30T01:00:18+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Visa EB-5 peligra en el estado de California","datePublished":"2015-11-10T17:55:03+00:00","dateModified":"2025-10-30T01:00:18+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/"},"wordCount":313,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/#primaryimage"},"thumbnailUrl":"","articleSection":["Tr\u00e1mites"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/","url":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/","name":"Visa EB-5 peligra en el estado de California","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-11-10T17:55:03+00:00","dateModified":"2025-10-30T01:00:18+00:00","description":"La Visa EB-5 otorga la nacionalidad estadounidense a inmigrantes que inviertan en alg\u00fan negocio de EE UU y generen empleos, sin embargo buscan eliminarla.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/visa-eb-5-peligra-en-el-estado-de-california\/tramites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Tr\u00e1mites","item":"https:\/\/accesolatino.org\/category\/tramites\/"},{"@type":"ListItem","position":3,"name":"Visa EB-5 peligra en el estado de California"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12194"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12194\/revisions"}],"predecessor-version":[{"id":68029,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12194\/revisions\/68029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}