{"id":12189,"date":"2015-11-06T11:55:12","date_gmt":"2015-11-06T17:55:12","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2450"},"modified":"2025-10-29T19:04:59","modified_gmt":"2025-10-30T01:04:59","slug":"programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/","title":{"rendered":"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado"},"content":{"rendered":"<p>The <strong>Programa de Refugiados y Permisos para Ni\u00f1os Menores Centroamericanos<\/strong>, anunciado en octubre de 2014 por el gobierno de Estados Unidos, no registra ning\u00fan ingreso hasta ahora.<\/p>\n<p>Este programa de refugiados est\u00e1 destinado para ni\u00f1os centroamericanos que huyen de la violencia en sus pa\u00edses de origen y fue anunciado por el gobierno tras la crisis migratoria del a\u00f1o fiscal 2014, cuando la <strong>Patrulla Fronteriza<\/strong> detuvo a poco m\u00e1s de <strong>68 mil ni\u00f1os indocumentados que viajaban solos<\/strong> en la frontera con M\u00e9xico.<\/p>\n<p>El programa para dar estatus de refugiados a menores de edad provenientes de Honduras, Guatemala y El Salvador no registra ning\u00fan beneficiado a\u00fan, sin embargo el gobierno estadounidense asegura que se est\u00e1n dando los pasos adecuados para que los resultados comiencen a verse en poco tiempo.<\/p>\n<p>La iniciativa, activada en diciembre de 2014, se\u00f1ala que aquellos padres que se encuentren con un estatus migratorio en Estados Unidos y sus hijos residan en Centroam\u00e9rica, pueden solicitar el estatus de refugiados y, una vez concedido el beneficio, ser trasladados a territorio estadounidense sin tener que correr los riesgos de hacer la traves\u00eda por tierra. Pero el plan no ha funcionado, pues hasta la fecha ning\u00fan menor centroamericano ha entrado al pa\u00eds como refugiado.<\/p>\n<p>El plan lo ejecuta el <strong>Departamento de Seguridad Nacional<\/strong> (<strong>DHS<\/strong>, por sus siglas en ingl\u00e9s), quien determina si los peticionarios cumplen con los requisitos para reunirse con sus parientes como refugiados en Estados Unidos.<\/p>\n<p>Seg\u00fan datos del <strong>Departamento de Estado<\/strong>, hasta ahora cerca de <strong>5 mil 400 solicitudes de refugio han sido presentadas<\/strong>, de las cuales la mayor\u00eda argumentan que tratan de huir de las pandillas callejeras, la extorsi\u00f3n y asalto sexual, principalmente en El Salvador.<\/p>\n<p>Funcionarios de <strong>DHS<\/strong> han entrevistado, hasta el momento, solamente a 90 ni\u00f1os; siendo el procedimiento para obtener estatus de refugiados y el procesamiento de tr\u00e1mites la principal causa del retraso en las solicitudes que ya fueron aprobadas.<\/p>\n<p>Lavinia Lim\u00f3n, presidente y director ejecutivo del<strong> Comit\u00e9 Estadounidense para los Refugiados e Inmigrantes<\/strong>, dijo que \u201ces pat\u00e9tico que ning\u00fan ni\u00f1o ha llegado a trav\u00e9s de este programa\u201d.<\/p>\n<p>Fuente: <em>The New York Times, La Raza<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>El Programa de Refugiados y Permisos para Ni\u00f1os Menores Centroamericanos, anunciado en octubre de 2014 por el gobierno de Estados Unidos, no registra ning\u00fan ingreso hasta ahora. Este programa de refugiados est\u00e1 destinado para ni\u00f1os centroamericanos que huyen de la violencia en sus pa\u00edses de origen y fue anunciado por el gobierno tras la crisis migratoria del a\u00f1o fiscal 2014, cuando la Patrulla Fronteriza detuvo a poco m\u00e1s de 68 mil ni\u00f1os indocumentados que viajaban solos en la frontera con M\u00e9xico. El programa para dar estatus de refugiados a menores de edad provenientes de Honduras, Guatemala y El Salvador no registra ning\u00fan beneficiado a\u00fan, sin embargo el gobierno estadounidense asegura que se est\u00e1n dando los pasos adecuados para que los resultados comiencen a verse en poco tiempo. La iniciativa, activada en diciembre de 2014, se\u00f1ala que aquellos padres que se encuentren con un estatus migratorio en Estados Unidos y sus hijos residan en Centroam\u00e9rica, pueden solicitar el estatus de refugiados y, una vez concedido el beneficio, ser trasladados a territorio estadounidense sin tener que correr los riesgos de hacer la traves\u00eda por tierra. Pero el plan no ha funcionado, pues hasta la fecha ning\u00fan menor centroamericano ha entrado al pa\u00eds como refugiado. El plan lo ejecuta el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), quien determina si los peticionarios cumplen con los requisitos para reunirse con sus parientes como refugiados en Estados Unidos. Seg\u00fan datos del Departamento de Estado, hasta ahora cerca de 5 mil 400 solicitudes de refugio han sido presentadas, de las cuales la mayor\u00eda argumentan que tratan de huir de las pandillas callejeras, la extorsi\u00f3n y asalto sexual, principalmente en El Salvador. Funcionarios de DHS han entrevistado, hasta el momento, solamente a 90 ni\u00f1os; siendo el procedimiento para obtener estatus de refugiados y el procesamiento de tr\u00e1mites la principal causa del retraso en las solicitudes que ya fueron aprobadas. Lavinia Lim\u00f3n, presidente y director ejecutivo del Comit\u00e9 Estadounidense para los Refugiados e Inmigrantes, dijo que \u201ces pat\u00e9tico que ning\u00fan ni\u00f1o ha llegado a trav\u00e9s de este programa\u201d. Fuente: The New York Times, La Raza<\/p>","protected":false},"author":13,"featured_media":2451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado<\/title>\n<meta name=\"description\" content=\"El Programa de Refugiados y Permisos para Ni\u00f1os Menores Centroamericanos, anunciado en 2014 por el gobierno de EE UU, a\u00fan no registra ning\u00fan ingreso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado\" \/>\n<meta property=\"og:description\" content=\"El Programa de Refugiados y Permisos para Ni\u00f1os Menores Centroamericanos, anunciado en 2014 por el gobierno de EE UU, a\u00fan no registra ning\u00fan ingreso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-06T17:55:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:04:59+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado\",\"datePublished\":\"2015-11-06T17:55:12+00:00\",\"dateModified\":\"2025-10-30T01:04:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/\"},\"wordCount\":380,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/\",\"name\":\"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-11-06T17:55:12+00:00\",\"dateModified\":\"2025-10-30T01:04:59+00:00\",\"description\":\"El Programa de Refugiados y Permisos para Ni\u00f1os Menores Centroamericanos, anunciado en 2014 por el gobierno de EE UU, a\u00fan no registra ning\u00fan ingreso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado","description":"El Programa de Refugiados y Permisos para Ni\u00f1os Menores Centroamericanos, anunciado en 2014 por el gobierno de EE UU, a\u00fan no registra ning\u00fan ingreso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado","og_description":"El Programa de Refugiados y Permisos para Ni\u00f1os Menores Centroamericanos, anunciado en 2014 por el gobierno de EE UU, a\u00fan no registra ning\u00fan ingreso.","og_url":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-11-06T17:55:12+00:00","article_modified_time":"2025-10-30T01:04:59+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado","datePublished":"2015-11-06T17:55:12+00:00","dateModified":"2025-10-30T01:04:59+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/"},"wordCount":380,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/","url":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/","name":"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-11-06T17:55:12+00:00","dateModified":"2025-10-30T01:04:59+00:00","description":"El Programa de Refugiados y Permisos para Ni\u00f1os Menores Centroamericanos, anunciado en 2014 por el gobierno de EE UU, a\u00fan no registra ning\u00fan ingreso.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/programa-de-refugiados-para-ninos-centroamericanos-no-ha-funcionado\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Programa de refugiados para ni\u00f1os centroamericanos no ha funcionado"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12189"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12189\/revisions"}],"predecessor-version":[{"id":68035,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12189\/revisions\/68035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}