{"id":12188,"date":"2015-11-05T16:55:17","date_gmt":"2015-11-05T22:55:17","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2444"},"modified":"2025-10-29T19:05:25","modified_gmt":"2025-10-30T01:05:25","slug":"inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/","title":{"rendered":"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza"},"content":{"rendered":"<p>Un fallo judicial emitido la semana pasada por un tribunal de California ordena que los inmigrantes detenidos en centros del <strong>Servicio de Inmigraci\u00f3n y Control de Aduanas de los Estados Unidos<\/strong> (<strong>ICE<\/strong>, por sus siglas en ingl\u00e9s) <strong>podr\u00e1n tener derecho a audiencias de fianza<\/strong>.<\/p>\n<p>La decisi\u00f3n permitir\u00e1 que <strong>inmigrantes detenidos por m\u00e1s de seis meses<\/strong> en dichos centros reciban audiencias de fianza, lo que <strong>ayudar\u00e1 a que esperen en libertad la resoluci\u00f3n de sus casos<\/strong>. La <strong>Uni\u00f3n Americana de Libertades Civiles<\/strong> (<strong>ACLU<\/strong>, por sus siglas en ingl\u00e9s) del Sur de California interpuso inicialmente la demanda en 2007, y en noviembre de 2012 present\u00f3 otra, antecedentes que determinaron el fallo.<\/p>\n<p>La resoluci\u00f3n <strong>tambi\u00e9n favorece a inmigrantes retenidos por m\u00e1s de un a\u00f1o<\/strong>, quienes <strong>deber\u00e1n tener derecho a una audiencia de fianza cada seis meses<\/strong>, donde el gobierno tendr\u00e1 que demostrar por qu\u00e9 debe mantenerlos detenidos.<\/p>\n<p>Ezequiel Hern\u00e1ndez, abogado, dijo al respecto que \u201cel fallo ampl\u00eda la habilidad de personas detenidas en un centro de detenci\u00f3n de inmigraci\u00f3n, tanto para quienes no sean elegibles para una fianza o a quienes se las negaron, quienes podr\u00e1n volver a pedir una audiencia cada seis meses\u201d.<\/p>\n<p>Hern\u00e1ndez apunt\u00f3 que durante una audiencia de fianza <strong>los inmigrantes tienen el derecho de pedir a un juez que les permita pasar el proceso judicial en libertad<\/strong>. El abogado explic\u00f3 que el monto de la fianza se paga con un cheque de caja a nombre del <strong>Departamento de Seguridad Nacional<\/strong> (<strong>DHS<\/strong>, por sus siglas en ingl\u00e9s). Respecto a cu\u00e1ndo ejercer el derecho a pedir la audiencia de fianza, explic\u00f3 que <strong>el inmigrante puede hacerlo cuando acuda al tribunal o por medio de un escrito en el centro de detenci\u00f3n en el que se encuentra<\/strong>. \u201cLo m\u00e1s probable es que para asegurar el tr\u00e1mite el inmigrante necesite un abogado para que lo represente y determine si el fallo lo favorece\u201d, puntualiz\u00f3.<\/p>\n<p>El dictamen del tribunal fue recibido de buena manera por activistas y organizaciones que defienden los derechos de los inmigrantes. Juan Jos\u00e9 Guti\u00e9rrez, presidente del Movimiento Latino USA en Los Angeles, California, dijo que \u201ces una victoria para los estados que son cubiertos por el Noveno Circuito y un ejemplo a seguir por el resto del sistema judicial de Estadios Unidos. Los detenidos corr\u00edan el riesgo de ser olvidados y pasarse tiempos que nunca se pod\u00edan saber con certeza\u201d.<\/p>\n<p>Fuente: <em>Univisi\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Un fallo judicial emitido la semana pasada por un tribunal de California ordena que los inmigrantes detenidos en centros del Servicio de Inmigraci\u00f3n y Control de Aduanas de los Estados Unidos (ICE, por sus siglas en ingl\u00e9s) podr\u00e1n tener derecho a audiencias de fianza. La decisi\u00f3n permitir\u00e1 que inmigrantes detenidos por m\u00e1s de seis meses en dichos centros reciban audiencias de fianza, lo que ayudar\u00e1 a que esperen en libertad la resoluci\u00f3n de sus casos. La Uni\u00f3n Americana de Libertades Civiles (ACLU, por sus siglas en ingl\u00e9s) del Sur de California interpuso inicialmente la demanda en 2007, y en noviembre de 2012 present\u00f3 otra, antecedentes que determinaron el fallo. La resoluci\u00f3n tambi\u00e9n favorece a inmigrantes retenidos por m\u00e1s de un a\u00f1o, quienes deber\u00e1n tener derecho a una audiencia de fianza cada seis meses, donde el gobierno tendr\u00e1 que demostrar por qu\u00e9 debe mantenerlos detenidos. Ezequiel Hern\u00e1ndez, abogado, dijo al respecto que \u201cel fallo ampl\u00eda la habilidad de personas detenidas en un centro de detenci\u00f3n de inmigraci\u00f3n, tanto para quienes no sean elegibles para una fianza o a quienes se las negaron, quienes podr\u00e1n volver a pedir una audiencia cada seis meses\u201d. Hern\u00e1ndez apunt\u00f3 que durante una audiencia de fianza los inmigrantes tienen el derecho de pedir a un juez que les permita pasar el proceso judicial en libertad. El abogado explic\u00f3 que el monto de la fianza se paga con un cheque de caja a nombre del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s). Respecto a cu\u00e1ndo ejercer el derecho a pedir la audiencia de fianza, explic\u00f3 que el inmigrante puede hacerlo cuando acuda al tribunal o por medio de un escrito en el centro de detenci\u00f3n en el que se encuentra. \u201cLo m\u00e1s probable es que para asegurar el tr\u00e1mite el inmigrante necesite un abogado para que lo represente y determine si el fallo lo favorece\u201d, puntualiz\u00f3. El dictamen del tribunal fue recibido de buena manera por activistas y organizaciones que defienden los derechos de los inmigrantes. Juan Jos\u00e9 Guti\u00e9rrez, presidente del Movimiento Latino USA en Los Angeles, California, dijo que \u201ces una victoria para los estados que son cubiertos por el Noveno Circuito y un ejemplo a seguir por el resto del sistema judicial de Estadios Unidos. Los detenidos corr\u00edan el riesgo de ser olvidados y pasarse tiempos que nunca se pod\u00edan saber con certeza\u201d. Fuente: Univisi\u00f3n<\/p>","protected":false},"author":13,"featured_media":2446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza<\/title>\n<meta name=\"description\" content=\"Un fallo judicial emitido por un tribunal de California ordena que los inmigrantes detenidos en centros del ICE podr\u00e1n tener derecho a audiencias de fianza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza\" \/>\n<meta property=\"og:description\" content=\"Un fallo judicial emitido por un tribunal de California ordena que los inmigrantes detenidos en centros del ICE podr\u00e1n tener derecho a audiencias de fianza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-05T22:55:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:05:25+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza\",\"datePublished\":\"2015-11-05T22:55:17+00:00\",\"dateModified\":\"2025-10-30T01:05:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/\"},\"wordCount\":429,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/\",\"name\":\"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-11-05T22:55:17+00:00\",\"dateModified\":\"2025-10-30T01:05:25+00:00\",\"description\":\"Un fallo judicial emitido por un tribunal de California ordena que los inmigrantes detenidos en centros del ICE podr\u00e1n tener derecho a audiencias de fianza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza","description":"Un fallo judicial emitido por un tribunal de California ordena que los inmigrantes detenidos en centros del ICE podr\u00e1n tener derecho a audiencias de fianza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza","og_description":"Un fallo judicial emitido por un tribunal de California ordena que los inmigrantes detenidos en centros del ICE podr\u00e1n tener derecho a audiencias de fianza.","og_url":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-11-05T22:55:17+00:00","article_modified_time":"2025-10-30T01:05:25+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza","datePublished":"2015-11-05T22:55:17+00:00","dateModified":"2025-10-30T01:05:25+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/"},"wordCount":429,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/","url":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/","name":"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-11-05T22:55:17+00:00","dateModified":"2025-10-30T01:05:25+00:00","description":"Un fallo judicial emitido por un tribunal de California ordena que los inmigrantes detenidos en centros del ICE podr\u00e1n tener derecho a audiencias de fianza.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/inmigrantes-en-centros-de-detencion-tendran-derecho-a-fianza\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Inmigrantes en centros de detenci\u00f3n tendr\u00e1n derecho a fianza"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12188"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12188\/revisions"}],"predecessor-version":[{"id":68036,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12188\/revisions\/68036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}