{"id":12175,"date":"2015-10-27T11:55:53","date_gmt":"2015-10-27T17:55:53","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2387"},"modified":"2025-10-29T19:08:15","modified_gmt":"2025-10-30T01:08:15","slug":"plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/","title":{"rendered":"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas"},"content":{"rendered":"<p>The <strong>Plan Frontera Sur<\/strong>, ideado por el gobierno estadounidense para detener el paso de los inmigrantes centroamericanos mientras transitan de M\u00e9xico a Estados Unidos (EE UU), ha sido calificado como \u201cobsoleto, injusto e inhumano\u201d por diversos activistas e instituciones pro inmigrantes.<\/p>\n<p>Cada d\u00eda, cientos de inmigrantes centroamericanos salen de sus pa\u00edses escapando de la violencia. El <strong>Plan Frontera Sur<\/strong> tiene por objetivo frenarles el paso por M\u00e9xico hacia EE UU para deportarlos, acto que, seg\u00fan activistas, no resuelve la crisis en la regi\u00f3n.<\/p>\n<p>Previo a presentar su informe ante la<strong> Comisi\u00f3n Interamericana de Derechos Humanos<\/strong> (<strong>CIDH<\/strong>), activistas de la <strong>Misi\u00f3n Internacional de Verificaci\u00f3n sobre los derechos humanos de migrantes en Honduras<\/strong>, afirmaron que EE UU tiene parte de responsabilidad en resolver la crisis y dar un trato digno a quienes buscan refugio en el pa\u00eds norteamericano.<\/p>\n<p>Mayra Alarc\u00f3n, miembro de la <strong>Oficina Regional para Centroam\u00e9rica y M\u00e9xico del grupo Consejer\u00eda de Proyectos<\/strong> (PCS) dijo: \u201cNos preocupa que esta crisis se vuelva invisible; la gente sigue saliendo para salvar sus vidas. Los derechos no tienen fronteras y que la gente salga sin visa no los priva de que EEUU, y los dem\u00e1s gobiernos, los protejan\u201d.<\/p>\n<p>Alarc\u00f3n argument\u00f3 que \u201ctodos los d\u00edas est\u00e1n saliendo cientos y miles de centroamericanos (<strong>45 mil 500 han sido deportados desde M\u00e9xico a Honduras entre enero y junio de este a\u00f1o<\/strong>), y EE UU debe hacer una lectura m\u00e1s adecuada de la realidad en la zona, dejar de ver a los inmigrantes como un problema de seguridad nacional y dar una respuesta integral a la crisis\u201d.<\/p>\n<p>Por su parte, Patricia Montes, directora ejecutiva del Centro Presente en Boston, Massachusetts y miembro de la red <strong>Alianza Am\u00e9ricas<\/strong>, se\u00f1al\u00f3 que el sistema migratorio de EE UU \u201ces obsoleto, injusto e inhumano\u201d, ya que, coment\u00f3, si bien los pa\u00edses tienen derecho a resguardar sus fronteras, debe ser \u201csiempre y cuando no se violen los derechos humanos de las personas\u201d.<\/p>\n<p>En Centroam\u00e9rica, la violencia sigue causando desplazamiento interno y migraci\u00f3n forzada, por lo que los activistas urgieron tanto al gobierno de EE UU como a la comunidad internacional que no permitan que el problema \u201cse vuelva invisible\u201d.<\/p>\n<p>Fuente: <em>La Raza<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>El Plan Frontera Sur, ideado por el gobierno estadounidense para detener el paso de los inmigrantes centroamericanos mientras transitan de M\u00e9xico a Estados Unidos (EE UU), ha sido calificado como \u201cobsoleto, injusto e inhumano\u201d por diversos activistas e instituciones pro inmigrantes. Cada d\u00eda, cientos de inmigrantes centroamericanos salen de sus pa\u00edses escapando de la violencia. El Plan Frontera Sur tiene por objetivo frenarles el paso por M\u00e9xico hacia EE UU para deportarlos, acto que, seg\u00fan activistas, no resuelve la crisis en la regi\u00f3n. Previo a presentar su informe ante la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH), activistas de la Misi\u00f3n Internacional de Verificaci\u00f3n sobre los derechos humanos de migrantes en Honduras, afirmaron que EE UU tiene parte de responsabilidad en resolver la crisis y dar un trato digno a quienes buscan refugio en el pa\u00eds norteamericano. Mayra Alarc\u00f3n, miembro de la Oficina Regional para Centroam\u00e9rica y M\u00e9xico del grupo Consejer\u00eda de Proyectos (PCS) dijo: \u201cNos preocupa que esta crisis se vuelva invisible; la gente sigue saliendo para salvar sus vidas. Los derechos no tienen fronteras y que la gente salga sin visa no los priva de que EEUU, y los dem\u00e1s gobiernos, los protejan\u201d. Alarc\u00f3n argument\u00f3 que \u201ctodos los d\u00edas est\u00e1n saliendo cientos y miles de centroamericanos (45 mil 500 han sido deportados desde M\u00e9xico a Honduras entre enero y junio de este a\u00f1o), y EE UU debe hacer una lectura m\u00e1s adecuada de la realidad en la zona, dejar de ver a los inmigrantes como un problema de seguridad nacional y dar una respuesta integral a la crisis\u201d. Por su parte, Patricia Montes, directora ejecutiva del Centro Presente en Boston, Massachusetts y miembro de la red Alianza Am\u00e9ricas, se\u00f1al\u00f3 que el sistema migratorio de EE UU \u201ces obsoleto, injusto e inhumano\u201d, ya que, coment\u00f3, si bien los pa\u00edses tienen derecho a resguardar sus fronteras, debe ser \u201csiempre y cuando no se violen los derechos humanos de las personas\u201d. En Centroam\u00e9rica, la violencia sigue causando desplazamiento interno y migraci\u00f3n forzada, por lo que los activistas urgieron tanto al gobierno de EE UU como a la comunidad internacional que no permitan que el problema \u201cse vuelva invisible\u201d. Fuente: La Raza<\/p>","protected":false},"author":13,"featured_media":2388,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas<\/title>\n<meta name=\"description\" content=\"El Plan Frontera Sur, ideado para detener inmigrantes centroamericanos, fue calificado como \u201cobsoleto, injusto e inhumano\u201d por activistas pro inmigrantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas\" \/>\n<meta property=\"og:description\" content=\"El Plan Frontera Sur, ideado para detener inmigrantes centroamericanos, fue calificado como \u201cobsoleto, injusto e inhumano\u201d por activistas pro inmigrantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-27T17:55:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:08:15+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas\",\"datePublished\":\"2015-10-27T17:55:53+00:00\",\"dateModified\":\"2025-10-30T01:08:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/\"},\"wordCount\":394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/\",\"name\":\"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-10-27T17:55:53+00:00\",\"dateModified\":\"2025-10-30T01:08:15+00:00\",\"description\":\"El Plan Frontera Sur, ideado para detener inmigrantes centroamericanos, fue calificado como \u201cobsoleto, injusto e inhumano\u201d por activistas pro inmigrantes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas","description":"El Plan Frontera Sur, ideado para detener inmigrantes centroamericanos, fue calificado como \u201cobsoleto, injusto e inhumano\u201d por activistas pro inmigrantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas","og_description":"El Plan Frontera Sur, ideado para detener inmigrantes centroamericanos, fue calificado como \u201cobsoleto, injusto e inhumano\u201d por activistas pro inmigrantes.","og_url":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-10-27T17:55:53+00:00","article_modified_time":"2025-10-30T01:08:15+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas","datePublished":"2015-10-27T17:55:53+00:00","dateModified":"2025-10-30T01:08:15+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/"},"wordCount":394,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/","url":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/","name":"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-10-27T17:55:53+00:00","dateModified":"2025-10-30T01:08:15+00:00","description":"El Plan Frontera Sur, ideado para detener inmigrantes centroamericanos, fue calificado como \u201cobsoleto, injusto e inhumano\u201d por activistas pro inmigrantes.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/plan-frontera-sur-no-resuelve-la-crisis-en-centroamerica-activistas\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Plan Frontera Sur no resuelve la crisis en Centroam\u00e9rica: activistas"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12175"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12175\/revisions"}],"predecessor-version":[{"id":68053,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12175\/revisions\/68053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}