{"id":12173,"date":"2015-10-26T11:55:51","date_gmt":"2015-10-26T16:55:51","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2378"},"modified":"2025-10-29T19:08:34","modified_gmt":"2025-10-30T01:08:34","slug":"inmigrantes-campesinos-de-california-exigen-daca-y-dapa","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/","title":{"rendered":"Inmigrantes campesinos de California exigen DACA Y DAPA"},"content":{"rendered":"<p>El pasado 20 de octubre, inmigrantes trabajadores del campo y activistas comunitarios exigieron que se autorice la aplicaci\u00f3n de <strong>DACA<\/strong> and <strong>DAPA<\/strong>, dos alivios migratorios administrativos suspendidos por orden de un juez; su protesta fue realizada en el Valle Central de California, frente a un centro de detenci\u00f3n de inmigrantes indocumentados del <strong>Servicio de Inmigraci\u00f3n y Control de Aduanas de los Estados Unidos<\/strong> (<strong>ICE<\/strong>, por sus siglas en ingl\u00e9s).<\/p>\n<p>El grupo de inmigrantes, miembros de la <strong>Fundaci\u00f3n Uni\u00f3n de Campesinos<\/strong> (<strong>UFW<\/strong>) y activistas de la <strong>Coalici\u00f3n Kern para Ciudadan\u00eda<\/strong> protestaron frente al Centro de Detenci\u00f3n Mesa Verde en Bakersfield y pidieron que se permita la aplicaci\u00f3n de la <strong>Acci\u00f3n Diferida para Padres<\/strong> (<strong>DAPA<\/strong>) y una extensi\u00f3n de la <strong>Acci\u00f3n Diferida para los Llegados en la Infancia<\/strong> (<strong>DACA<\/strong>).<\/p>\n<p>Diana Tellefson Torres, directora ejecutiva de la <strong>Fundaci\u00f3n UFW<\/strong>, coment\u00f3 que \u201cno podemos dejar a los trabajadores agrarios y a otros inmigrantes la sensaci\u00f3n de inestabilidad de que una vez que salgan a trabajar puede que no regresen con sus familias debido a la deportaci\u00f3n\u201d.<\/p>\n<p>Por su parte, la <strong>Coalici\u00f3n Kern<\/strong> apunt\u00f3 que \u201cactualmente hay millones de indocumentados que han estado esperando por estos alivios administrativos (<strong>DACA<\/strong> and <strong>DAPA<\/strong>). Han esperado demasiado y nosotros, sus aliados, nos resistimos a esperar m\u00e1s tiempo\u201d.<\/p>\n<p>Los alivios administrativos (<strong>DACA<\/strong> and <strong>DAPA<\/strong>) fueron emitidos por el gobierno estadounidense en noviembre de 2014, sin embargo, fueron suspendidos en febrero de 2015 debido a una demanda presentada por 26 estados del pa\u00eds ante una corte de Texas.<\/p>\n<p>El pasado mes de abril, la Corte de Apelaciones del Quinto Circuito, ratific\u00f3 la suspensi\u00f3n de la aplicaci\u00f3n de las medidas administrativas de alivio migratorio y se espera que la corte se pronuncie esta semana sobre el tema.<\/p>\n<p>Fuente: <em>La Opini\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>El pasado 20 de octubre, inmigrantes trabajadores del campo y activistas comunitarios exigieron que se autorice la aplicaci\u00f3n de DACA y DAPA, dos alivios migratorios administrativos suspendidos por orden de un juez; su protesta fue realizada en el Valle Central de California, frente a un centro de detenci\u00f3n de inmigrantes indocumentados del Servicio de Inmigraci\u00f3n y Control de Aduanas de los Estados Unidos (ICE, por sus siglas en ingl\u00e9s). El grupo de inmigrantes, miembros de la Fundaci\u00f3n Uni\u00f3n de Campesinos (UFW) y activistas de la Coalici\u00f3n Kern para Ciudadan\u00eda protestaron frente al Centro de Detenci\u00f3n Mesa Verde en Bakersfield y pidieron que se permita la aplicaci\u00f3n de la Acci\u00f3n Diferida para Padres (DAPA) y una extensi\u00f3n de la Acci\u00f3n Diferida para los Llegados en la Infancia (DACA). Diana Tellefson Torres, directora ejecutiva de la Fundaci\u00f3n UFW, coment\u00f3 que \u201cno podemos dejar a los trabajadores agrarios y a otros inmigrantes la sensaci\u00f3n de inestabilidad de que una vez que salgan a trabajar puede que no regresen con sus familias debido a la deportaci\u00f3n\u201d. Por su parte, la Coalici\u00f3n Kern apunt\u00f3 que \u201cactualmente hay millones de indocumentados que han estado esperando por estos alivios administrativos (DACA y DAPA). Han esperado demasiado y nosotros, sus aliados, nos resistimos a esperar m\u00e1s tiempo\u201d. Los alivios administrativos (DACA y DAPA) fueron emitidos por el gobierno estadounidense en noviembre de 2014, sin embargo, fueron suspendidos en febrero de 2015 debido a una demanda presentada por 26 estados del pa\u00eds ante una corte de Texas. El pasado mes de abril, la Corte de Apelaciones del Quinto Circuito, ratific\u00f3 la suspensi\u00f3n de la aplicaci\u00f3n de las medidas administrativas de alivio migratorio y se espera que la corte se pronuncie esta semana sobre el tema. Fuente: La Opini\u00f3n<\/p>","protected":false},"author":13,"featured_media":2379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inmigrantes campesinos de California exigen DACA Y DAPA<\/title>\n<meta name=\"description\" content=\"Inmigrantes trabajadores del campo y activistas exigieron que se autorice la aplicaci\u00f3n de DACA y DAPA, alivios migratorios suspendidos por orden del juez.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inmigrantes campesinos de California exigen DACA Y DAPA\" \/>\n<meta property=\"og:description\" content=\"Inmigrantes trabajadores del campo y activistas exigieron que se autorice la aplicaci\u00f3n de DACA y DAPA, alivios migratorios suspendidos por orden del juez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-26T16:55:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:08:34+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Inmigrantes campesinos de California exigen DACA Y DAPA\",\"datePublished\":\"2015-10-26T16:55:51+00:00\",\"dateModified\":\"2025-10-30T01:08:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/\",\"name\":\"Inmigrantes campesinos de California exigen DACA Y DAPA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-10-26T16:55:51+00:00\",\"dateModified\":\"2025-10-30T01:08:34+00:00\",\"description\":\"Inmigrantes trabajadores del campo y activistas exigieron que se autorice la aplicaci\u00f3n de DACA y DAPA, alivios migratorios suspendidos por orden del juez.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inmigrantes campesinos de California exigen DACA Y DAPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inmigrantes campesinos de California exigen DACA Y DAPA","description":"Inmigrantes trabajadores del campo y activistas exigieron que se autorice la aplicaci\u00f3n de DACA y DAPA, alivios migratorios suspendidos por orden del juez.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Inmigrantes campesinos de California exigen DACA Y DAPA","og_description":"Inmigrantes trabajadores del campo y activistas exigieron que se autorice la aplicaci\u00f3n de DACA y DAPA, alivios migratorios suspendidos por orden del juez.","og_url":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-10-26T16:55:51+00:00","article_modified_time":"2025-10-30T01:08:34+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Inmigrantes campesinos de California exigen DACA Y DAPA","datePublished":"2015-10-26T16:55:51+00:00","dateModified":"2025-10-30T01:08:34+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/","url":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/","name":"Inmigrantes campesinos de California exigen DACA Y DAPA","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-10-26T16:55:51+00:00","dateModified":"2025-10-30T01:08:34+00:00","description":"Inmigrantes trabajadores del campo y activistas exigieron que se autorice la aplicaci\u00f3n de DACA y DAPA, alivios migratorios suspendidos por orden del juez.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/inmigrantes-campesinos-de-california-exigen-daca-y-dapa\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Inmigrantes campesinos de California exigen DACA Y DAPA"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12173"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12173\/revisions"}],"predecessor-version":[{"id":68055,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12173\/revisions\/68055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}