{"id":12169,"date":"2015-10-22T11:55:17","date_gmt":"2015-10-22T16:55:17","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2358"},"modified":"2025-10-29T19:28:57","modified_gmt":"2025-10-30T01:28:57","slug":"ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/","title":{"rendered":"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos"},"content":{"rendered":"<p>El gobierno de Estados Unidos se encuentra considerando un proyecto de ley para <strong>retirar fondos federales a las conocidas como \u201cciudades santuario\u201d<\/strong>, que son principalmente iglesias e instituciones que funcionan como refugio para inmigrantes indocumentados.<\/p>\n<p>El t\u00e9rmino de \u201cciudad santuario\u201d proviene de los a\u00f1os ochenta, cuando muchas iglesias e instituciones religiosas decidieron acoger a refugiados de las guerras en Centroam\u00e9rica, primordialmente El Salvador y Guatemala. Durante mucho tiempo, el gobierno estadounidense se neg\u00f3 a dar asilo a refugiados de esos pa\u00edses, motivo por el que las \u201cciudades santuario\u201d tomaron esta medida. Actualmente y durante los \u00faltimos a\u00f1os, <strong>estas instituciones han refugiado a inmigrantes indocumentados que buscan protegerse de la deportaci\u00f3n<\/strong>.<\/p>\n<p>El proyecto de ley se refiere a 326 condados, 32 ciudades y 4 estados que han aprobado leyes locales para limitar la colaboraci\u00f3n entre polic\u00edas de esas localidades y las autoridades migratorias federales. Un ejemplo es el caso del <strong>California \u201cTrust Act\u201d<\/strong> una ley promulgada en el estado hace dos a\u00f1os con el objetivo de prohibir que las autoridades locales detengan a inmigrantes con el \u00fanico fin de entregarlos a las autoridades migratorias; con la excepci\u00f3n de inmigrantes que hayan cometido alg\u00fan delito.<\/p>\n<p>Cabe resaltar que a\u00fan dentro de las \u201cciudades santuario\u201d, <strong>los indocumentados siguen siendo vulnerables a detenci\u00f3n por parte de las autoridades migratorias, sobre todo si cometen un delito<\/strong>. Ninguna ley local protege a una persona con estatus migratorio irregular de ser detenida por agentes migratorios. Lo \u00fanico que hacen estas leyes es impedir que las polic\u00edas locales puedan detener a un indocumentado que no debe estar detenido bajo la ley penal \u00fanicamente por su estatus migratorio.<\/p>\n<p>Fuente: <em>El Diario NY<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>El gobierno de Estados Unidos se encuentra considerando un proyecto de ley para retirar fondos federales a las conocidas como \u201cciudades santuario\u201d, que son principalmente iglesias e instituciones que funcionan como refugio para inmigrantes indocumentados. El t\u00e9rmino de \u201cciudad santuario\u201d proviene de los a\u00f1os ochenta, cuando muchas iglesias e instituciones religiosas decidieron acoger a refugiados de las guerras en Centroam\u00e9rica, primordialmente El Salvador y Guatemala. Durante mucho tiempo, el gobierno estadounidense se neg\u00f3 a dar asilo a refugiados de esos pa\u00edses, motivo por el que las \u201cciudades santuario\u201d tomaron esta medida. Actualmente y durante los \u00faltimos a\u00f1os, estas instituciones han refugiado a inmigrantes indocumentados que buscan protegerse de la deportaci\u00f3n. El proyecto de ley se refiere a 326 condados, 32 ciudades y 4 estados que han aprobado leyes locales para limitar la colaboraci\u00f3n entre polic\u00edas de esas localidades y las autoridades migratorias federales. Un ejemplo es el caso del California \u201cTrust Act\u201d una ley promulgada en el estado hace dos a\u00f1os con el objetivo de prohibir que las autoridades locales detengan a inmigrantes con el \u00fanico fin de entregarlos a las autoridades migratorias; con la excepci\u00f3n de inmigrantes que hayan cometido alg\u00fan delito. Cabe resaltar que a\u00fan dentro de las \u201cciudades santuario\u201d, los indocumentados siguen siendo vulnerables a detenci\u00f3n por parte de las autoridades migratorias, sobre todo si cometen un delito. Ninguna ley local protege a una persona con estatus migratorio irregular de ser detenida por agentes migratorios. Lo \u00fanico que hacen estas leyes es impedir que las polic\u00edas locales puedan detener a un indocumentado que no debe estar detenido bajo la ley penal \u00fanicamente por su estatus migratorio. Fuente: El Diario NY<\/p>","protected":false},"author":13,"featured_media":2359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos<\/title>\n<meta name=\"description\" content=\"El gobierno de Estados Unidos se encuentra considerando un proyecto de ley para retirar fondos federales a las conocidas como \u201cciudades santuario\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos\" \/>\n<meta property=\"og:description\" content=\"El gobierno de Estados Unidos se encuentra considerando un proyecto de ley para retirar fondos federales a las conocidas como \u201cciudades santuario\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-22T16:55:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:28:57+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos\",\"datePublished\":\"2015-10-22T16:55:17+00:00\",\"dateModified\":\"2025-10-30T01:28:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/\"},\"wordCount\":294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/\",\"name\":\"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-10-22T16:55:17+00:00\",\"dateModified\":\"2025-10-30T01:28:57+00:00\",\"description\":\"El gobierno de Estados Unidos se encuentra considerando un proyecto de ley para retirar fondos federales a las conocidas como \u201cciudades santuario\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos","description":"El gobierno de Estados Unidos se encuentra considerando un proyecto de ley para retirar fondos federales a las conocidas como \u201cciudades santuario\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos","og_description":"El gobierno de Estados Unidos se encuentra considerando un proyecto de ley para retirar fondos federales a las conocidas como \u201cciudades santuario\u201d.","og_url":"https:\/\/accesolatino.org\/en\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-10-22T16:55:17+00:00","article_modified_time":"2025-10-30T01:28:57+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos","datePublished":"2015-10-22T16:55:17+00:00","dateModified":"2025-10-30T01:28:57+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/"},"wordCount":294,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/","url":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/","name":"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-10-22T16:55:17+00:00","dateModified":"2025-10-30T01:28:57+00:00","description":"El gobierno de Estados Unidos se encuentra considerando un proyecto de ley para retirar fondos federales a las conocidas como \u201cciudades santuario\u201d.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/ciudades-santuario-refugio-de-inmigrantes-cerca-de-quedar-sin-fondos\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"\u201cCiudades santuario\u201d, refugio de inmigrantes, cerca de quedar sin fondos"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12169"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12169\/revisions"}],"predecessor-version":[{"id":68061,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12169\/revisions\/68061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}