{"id":12167,"date":"2015-10-21T11:55:49","date_gmt":"2015-10-21T16:55:49","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2351"},"modified":"2025-10-29T19:30:45","modified_gmt":"2025-10-30T01:30:45","slug":"guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/","title":{"rendered":"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en EE UU"},"content":{"rendered":"<p>El pasado 20 de octubre, el <strong>Departamento de Educaci\u00f3n<\/strong> estadounidense divulg\u00f3 una gu\u00eda de recursos para que escuelas y universidades <strong>ayuden a j\u00f3venes indocumentados a obtener una educaci\u00f3n apropiada<\/strong>.<\/p>\n<p>De acuerdo a un comunicado del <strong>Departamento de Educaci\u00f3n<\/strong>, \u201clas escuelas p\u00fablicas deben ser lugares seguros de apoyo y bienvenida, donde todos los estudiantes, sin importar su c\u00f3digo postal o d\u00f3nde nacieron, tengan la oportunidad de tener \u00e9xito\u201d.<\/p>\n<p>La divulgaci\u00f3n de esta gu\u00eda se da tres a\u00f1os despu\u00e9s de la puesta en marcha del programa de \u201cacci\u00f3n diferida\u201d (<strong>DACA<\/strong>), que <strong>ha dotado de un estatus migratorio temporalmente a m\u00e1s de 680 mil estudiantes indocumentados<\/strong>. La gu\u00eda ofrece un repaso de los derechos de los estudiantes indocumentados; consejos para instructores en secundarias y universidades sobre c\u00f3mo ayudar a estos j\u00f3venes; informaci\u00f3n sobre ayuda financiera, as\u00ed como una lista de becas privadas que podr\u00edan beneficiar a la comunidad indocumentada.<\/p>\n<p>Otro de los objetivos que tiene la gu\u00eda, compuesta por m\u00e1s de 50 p\u00e1ginas, es alentar a las universidades a que abran sus puertas a los dreamers que se ampararon al <strong>DACA<\/strong> de 2012. Por ello, ofrece informaci\u00f3n y recursos para que los educadores y l\u00edderes acad\u00e9micos ayuden a mejorar el rendimiento de estudiantes en secundarias y universidades, particularmente de aquellos que, al ser indocumentados, tienen trabas particulares.<\/p>\n<p>Asimismo, la gu\u00eda ofrece informaci\u00f3n sobre programas educativos para adultos, financiados por el gobierno federal, y datos para estudiantes migrantes sobre c\u00f3mo acceder a sus archivos acad\u00e9micos al solicitar o renovar <strong>DACA<\/strong>.<\/p>\n<p>Se calcula que m\u00e1s de 1.5 millones de ni\u00f1os y j\u00f3venes indocumentados re\u00fanen los requisitos para ampararse al <strong>DACA<\/strong> de 2012, mientras que otros 400 mil ser\u00e1n elegibles en los pr\u00f3ximos a\u00f1os. Cabe destacar que muchos no hab\u00edan solicitado los beneficios del <strong>DACA<\/strong> debido a que a\u00fan no hab\u00edan cumplido la edad m\u00ednima de 15 a\u00f1os para someter una solicitud.<\/p>\n<p>Fuente: <em>La Raza<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>El pasado 20 de octubre, el Departamento de Educaci\u00f3n estadounidense divulg\u00f3 una gu\u00eda de recursos para que escuelas y universidades ayuden a j\u00f3venes indocumentados a obtener una educaci\u00f3n apropiada. De acuerdo a un comunicado del Departamento de Educaci\u00f3n, \u201clas escuelas p\u00fablicas deben ser lugares seguros de apoyo y bienvenida, donde todos los estudiantes, sin importar su c\u00f3digo postal o d\u00f3nde nacieron, tengan la oportunidad de tener \u00e9xito\u201d. La divulgaci\u00f3n de esta gu\u00eda se da tres a\u00f1os despu\u00e9s de la puesta en marcha del programa de \u201cacci\u00f3n diferida\u201d (DACA), que ha dotado de un estatus migratorio temporalmente a m\u00e1s de 680 mil estudiantes indocumentados. La gu\u00eda ofrece un repaso de los derechos de los estudiantes indocumentados; consejos para instructores en secundarias y universidades sobre c\u00f3mo ayudar a estos j\u00f3venes; informaci\u00f3n sobre ayuda financiera, as\u00ed como una lista de becas privadas que podr\u00edan beneficiar a la comunidad indocumentada. Otro de los objetivos que tiene la gu\u00eda, compuesta por m\u00e1s de 50 p\u00e1ginas, es alentar a las universidades a que abran sus puertas a los dreamers que se ampararon al DACA de 2012. Por ello, ofrece informaci\u00f3n y recursos para que los educadores y l\u00edderes acad\u00e9micos ayuden a mejorar el rendimiento de estudiantes en secundarias y universidades, particularmente de aquellos que, al ser indocumentados, tienen trabas particulares. Asimismo, la gu\u00eda ofrece informaci\u00f3n sobre programas educativos para adultos, financiados por el gobierno federal, y datos para estudiantes migrantes sobre c\u00f3mo acceder a sus archivos acad\u00e9micos al solicitar o renovar DACA. Se calcula que m\u00e1s de 1.5 millones de ni\u00f1os y j\u00f3venes indocumentados re\u00fanen los requisitos para ampararse al DACA de 2012, mientras que otros 400 mil ser\u00e1n elegibles en los pr\u00f3ximos a\u00f1os. Cabe destacar que muchos no hab\u00edan solicitado los beneficios del DACA debido a que a\u00fan no hab\u00edan cumplido la edad m\u00ednima de 15 a\u00f1os para someter una solicitud. Fuente: La Raza<\/p>","protected":false},"author":13,"featured_media":2352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en...<\/title>\n<meta name=\"description\" content=\"El Departamento de Educaci\u00f3n estadounidense divulg\u00f3 una gu\u00eda para que escuelas y universidades ayuden a j\u00f3venes indocumentados a obtener una educaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en...\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Educaci\u00f3n estadounidense divulg\u00f3 una gu\u00eda para que escuelas y universidades ayuden a j\u00f3venes indocumentados a obtener una educaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-21T16:55:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:30:45+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en EE UU\",\"datePublished\":\"2015-10-21T16:55:49+00:00\",\"dateModified\":\"2025-10-30T01:30:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/\"},\"wordCount\":354,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/\",\"name\":\"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en...\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-10-21T16:55:49+00:00\",\"dateModified\":\"2025-10-30T01:30:45+00:00\",\"description\":\"El Departamento de Educaci\u00f3n estadounidense divulg\u00f3 una gu\u00eda para que escuelas y universidades ayuden a j\u00f3venes indocumentados a obtener una educaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en EE UU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en...","description":"El Departamento de Educaci\u00f3n estadounidense divulg\u00f3 una gu\u00eda para que escuelas y universidades ayuden a j\u00f3venes indocumentados a obtener una educaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en...","og_description":"El Departamento de Educaci\u00f3n estadounidense divulg\u00f3 una gu\u00eda para que escuelas y universidades ayuden a j\u00f3venes indocumentados a obtener una educaci\u00f3n.","og_url":"https:\/\/accesolatino.org\/en\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-10-21T16:55:49+00:00","article_modified_time":"2025-10-30T01:30:45+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en EE UU","datePublished":"2015-10-21T16:55:49+00:00","dateModified":"2025-10-30T01:30:45+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/"},"wordCount":354,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/","url":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/","name":"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en...","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-10-21T16:55:49+00:00","dateModified":"2025-10-30T01:30:45+00:00","description":"El Departamento de Educaci\u00f3n estadounidense divulg\u00f3 una gu\u00eda para que escuelas y universidades ayuden a j\u00f3venes indocumentados a obtener una educaci\u00f3n.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/guia-sobre-derechos-de-estudiantes-indocumentados-es-divulgada-en-ee-uu\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Gu\u00eda sobre derechos de estudiantes indocumentados es divulgada en EE UU"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12167"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12167\/revisions"}],"predecessor-version":[{"id":68063,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12167\/revisions\/68063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}