{"id":12151,"date":"2015-10-09T11:55:16","date_gmt":"2015-10-09T16:55:16","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2282"},"modified":"2025-10-29T19:46:31","modified_gmt":"2025-10-30T01:46:31","slug":"plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/","title":{"rendered":"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU"},"content":{"rendered":"<p>Un par de plataformas de internet se han unido con la finalidad de ayudar a que m\u00e1s <strong>estudiantes inmigrantes puedan estudiar en universidades de Estados Unidos<\/strong>.<\/p>\n<p>El sitio mexicano <strong>Geek Education<\/strong> y el estadounidense <strong>Higher Ed Support<\/strong> se aliaron para crear <strong>Latin American Network for Higher Education<\/strong> (<strong>LANCO<\/strong>), una plataforma de mentores que <strong>ayudan a estudiantes inmigrantes en el proceso de aplicaci\u00f3n y admisi\u00f3n en universidades de Estados Unidos<\/strong>.<\/p>\n<p>Ambas plataformas cuentan con un equipo de expertos de varias nacionalidades; de acuerdo con Jim Dunn, co-fundador y responsable de alianzas con Universidades en <strong>LANCO<\/strong>, \u201c<strong>LANCO<\/strong> es resultado de la visi\u00f3n y uni\u00f3n de un experimentado equipo multinacional; que ha creado una amplia red de mentores acad\u00e9micos y aliados en distintas universidades que le permiten tener el conocimiento para guiar el proceso de aplicaci\u00f3n, incluyendo no s\u00f3lo a los colegios m\u00e1s famosos y reconocidos, sino a un amplio abanico de opciones que enriquecen las posibilidades y alternativas para los estudiantes inmigrantes\u201d.<\/p>\n<p>Las plataformas dieron a conocer la fusi\u00f3n el pasado mes de septiembre, teniendo el objetivo de ayudar a estudiantes de preparatoria extranjeros a ubicar una carrera y escuela en espec\u00edfico, a trav\u00e9s de asesor\u00eda, asistencia y mentor\u00eda.<\/p>\n<p>En este contexto, los estudiantes inmigrantes se ven seducidos a estudiar en el pa\u00eds norteamericano debido a la experiencia de vida, el valor curricular y la calidad de los programas. Adem\u00e1s, seg\u00fan un comunicado de las plataformas, <strong>Estados Unidos cuenta con un oferta de 4 mil universidades dispuestas a recibir a estudiantes inmigrantes<\/strong>.<\/p>\n<p>La plataforma funciona de la siguiente manera: cuando un estudiante la contacta, se le asigna un mentor experimentado, que trabajar\u00e1 muy de cerca con \u00e9l y su familia a trav\u00e9s de distintas herramientas de comunicaci\u00f3n a distancia con los siguientes objetivos:<\/p>\n<ul>\n<li>Creaci\u00f3n de un perfil del estudiante para elegir o ampliar las opciones educativas que mejor se adaptan a sus aptitudes, intereses e historial acad\u00e9mico.<\/li>\n<li>Calendarizar las actividades y requerimientos del proceso de selecci\u00f3n.<\/li>\n<li>Guiar en todo el proceso de aplicaci\u00f3n, desde recomendaciones para ensayos, llenado de formularios hasta cartas de recomendaci\u00f3n y reuni\u00f3n de documentaci\u00f3n.<\/li>\n<li>Acompa\u00f1ar al estudiante durante sus primeros 6 meses de estudio.<\/li>\n<\/ul>\n<p><strong>LANCO<\/strong> ofrece dos paquetes de acuerdo a las necesidades de los estudiantes y la informaci\u00f3n se puede consultar en<span style=\"color: #0000ff;\"> este sitio web<\/span>.<\/p>\n<p>Fuente: <em>ViveUSA<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Un par de plataformas de internet se han unido con la finalidad de ayudar a que m\u00e1s estudiantes inmigrantes puedan estudiar en universidades de Estados Unidos. El sitio mexicano Geek Education y el estadounidense Higher Ed Support se aliaron para crear Latin American Network for Higher Education (LANCO), una plataforma de mentores que ayudan a estudiantes inmigrantes en el proceso de aplicaci\u00f3n y admisi\u00f3n en universidades de Estados Unidos. Ambas plataformas cuentan con un equipo de expertos de varias nacionalidades; de acuerdo con Jim Dunn, co-fundador y responsable de alianzas con Universidades en LANCO, \u201cLANCO es resultado de la visi\u00f3n y uni\u00f3n de un experimentado equipo multinacional; que ha creado una amplia red de mentores acad\u00e9micos y aliados en distintas universidades que le permiten tener el conocimiento para guiar el proceso de aplicaci\u00f3n, incluyendo no s\u00f3lo a los colegios m\u00e1s famosos y reconocidos, sino a un amplio abanico de opciones que enriquecen las posibilidades y alternativas para los estudiantes inmigrantes\u201d. Las plataformas dieron a conocer la fusi\u00f3n el pasado mes de septiembre, teniendo el objetivo de ayudar a estudiantes de preparatoria extranjeros a ubicar una carrera y escuela en espec\u00edfico, a trav\u00e9s de asesor\u00eda, asistencia y mentor\u00eda. En este contexto, los estudiantes inmigrantes se ven seducidos a estudiar en el pa\u00eds norteamericano debido a la experiencia de vida, el valor curricular y la calidad de los programas. Adem\u00e1s, seg\u00fan un comunicado de las plataformas, Estados Unidos cuenta con un oferta de 4 mil universidades dispuestas a recibir a estudiantes inmigrantes. La plataforma funciona de la siguiente manera: cuando un estudiante la contacta, se le asigna un mentor experimentado, que trabajar\u00e1 muy de cerca con \u00e9l y su familia a trav\u00e9s de distintas herramientas de comunicaci\u00f3n a distancia con los siguientes objetivos: Creaci\u00f3n de un perfil del estudiante para elegir o ampliar las opciones educativas que mejor se adaptan a sus aptitudes, intereses e historial acad\u00e9mico. Calendarizar las actividades y requerimientos del proceso de selecci\u00f3n. Guiar en todo el proceso de aplicaci\u00f3n, desde recomendaciones para ensayos, llenado de formularios hasta cartas de recomendaci\u00f3n y reuni\u00f3n de documentaci\u00f3n. Acompa\u00f1ar al estudiante durante sus primeros 6 meses de estudio. LANCO ofrece dos paquetes de acuerdo a las necesidades de los estudiantes y la informaci\u00f3n se puede consultar en este sitio web. Fuente: ViveUSA<\/p>","protected":false},"author":13,"featured_media":2283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-12151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU<\/title>\n<meta name=\"description\" content=\"Dos plataformas de internet se unieron con la finalidad de ayudar a que m\u00e1s estudiantes inmigrantes puedan estudiar en universidades de Estados Unidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU\" \/>\n<meta property=\"og:description\" content=\"Dos plataformas de internet se unieron con la finalidad de ayudar a que m\u00e1s estudiantes inmigrantes puedan estudiar en universidades de Estados Unidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-09T16:55:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:46:31+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU\",\"datePublished\":\"2015-10-09T16:55:16+00:00\",\"dateModified\":\"2025-10-30T01:46:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/\"},\"wordCount\":416,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/\",\"name\":\"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-10-09T16:55:16+00:00\",\"dateModified\":\"2025-10-30T01:46:31+00:00\",\"description\":\"Dos plataformas de internet se unieron con la finalidad de ayudar a que m\u00e1s estudiantes inmigrantes puedan estudiar en universidades de Estados Unidos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\\\/educacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educaci\u00f3n\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/educacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU","description":"Dos plataformas de internet se unieron con la finalidad de ayudar a que m\u00e1s estudiantes inmigrantes puedan estudiar en universidades de Estados Unidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/","og_locale":"en_US","og_type":"article","og_title":"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU","og_description":"Dos plataformas de internet se unieron con la finalidad de ayudar a que m\u00e1s estudiantes inmigrantes puedan estudiar en universidades de Estados Unidos.","og_url":"https:\/\/accesolatino.org\/en\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-10-09T16:55:16+00:00","article_modified_time":"2025-10-30T01:46:31+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU","datePublished":"2015-10-09T16:55:16+00:00","dateModified":"2025-10-30T01:46:31+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/"},"wordCount":416,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/#primaryimage"},"thumbnailUrl":"","articleSection":["Educaci\u00f3n"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/","url":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/","name":"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-10-09T16:55:16+00:00","dateModified":"2025-10-30T01:46:31+00:00","description":"Dos plataformas de internet se unieron con la finalidad de ayudar a que m\u00e1s estudiantes inmigrantes puedan estudiar en universidades de Estados Unidos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/plataforma-facilita-admision-de-estudiantes-inmigrantes-en-ee-uu\/educacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Educaci\u00f3n","item":"https:\/\/accesolatino.org\/category\/educacion\/"},{"@type":"ListItem","position":3,"name":"Plataforma facilita admisi\u00f3n de estudiantes inmigrantes en EE UU"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12151"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12151\/revisions"}],"predecessor-version":[{"id":68081,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12151\/revisions\/68081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}