{"id":12123,"date":"2015-09-11T16:55:20","date_gmt":"2015-09-11T21:55:20","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2106"},"modified":"2025-10-29T20:59:36","modified_gmt":"2025-10-30T02:59:36","slug":"mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/","title":{"rendered":"M\u00e1s de 2 millones de deportados en lo que va del 2015"},"content":{"rendered":"<p>La administraci\u00f3n actual de Estados Unidos se encamina a registrar el n\u00famero de deportados m\u00e1s bajo de las tres \u00faltimas administraciones. L<strong>a cifra total de deportados hasta el 31 de agosto es de 2 millones 488 mil 302<\/strong>, seg\u00fan datos de la <strong>Oficina de Inmigraci\u00f3n y Aduanas<\/strong> (<strong>ICE<\/strong>, por sus siglas en ingl\u00e9s).<\/p>\n<p>La proyecci\u00f3n para los restantes 30 d\u00edas del a\u00f1o fiscal 2015, estimada en <strong>19 mil 478 deportaciones m\u00e1s<\/strong>, indica que al t\u00e9rmino del presente a\u00f1o fiscal la cifra alcanzar\u00e1 los <strong>233 mil 742 deportados<\/strong>, un 27% menos que las deportaciones registradas en 2014, cuando sumaron 315 mil 953.<\/p>\n<p>En junio pasado, se report\u00f3 que el n\u00famero de deportados hasta esa fecha era de 165 mil 283, con <strong>un promedio diario de 640 deportaciones<\/strong>. Las nuevas cifras elevan el <strong>promedio diario a 650 deportados<\/strong>.<\/p>\n<p><strong>ICE<\/strong> tambi\u00e9n explic\u00f3 que los pa\u00edses con mayor n\u00famero de deportados son: M\u00e9xico, con 132 mil 529; Guatemala, con 30 mil 807; El Salvador, con 19 mil 940; y <a href=\"https:\/\/accesolatino.org\/en\/121-indocumentados-hondurenos-fueron-deportados-de-estados-unidos\/\" target=\"_blank\" rel=\"noopener\">Honduras<\/a>, con 18 mil 445.<\/p>\n<p>El reporte del <strong>ICE<\/strong> tambi\u00e9n revel\u00f3 que a finales del mes de agosto fueron deportados 214 mil 264 inmigrantes indocumentados, de ellos, 126 mil 283 ten\u00eda antecedentes criminales (58.89%). El resto, 87 mil 981 (equivalente al 41.1%) no ten\u00eda antecedentes, dijo N\u00e9stor Yglesias, vocero de <strong>ICE<\/strong>.<\/p>\n<p>Fuente: <em>Univisi\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>La administraci\u00f3n actual de Estados Unidos se encamina a registrar el n\u00famero de deportados m\u00e1s bajo de las tres \u00faltimas administraciones. La cifra total de deportados hasta el 31 de agosto es de 2 millones 488 mil 302, seg\u00fan datos de la Oficina de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s). La proyecci\u00f3n para los restantes 30 d\u00edas del a\u00f1o fiscal 2015, estimada en 19 mil 478 deportaciones m\u00e1s, indica que al t\u00e9rmino del presente a\u00f1o fiscal la cifra alcanzar\u00e1 los 233 mil 742 deportados, un 27% menos que las deportaciones registradas en 2014, cuando sumaron 315 mil 953. En junio pasado, se report\u00f3 que el n\u00famero de deportados hasta esa fecha era de 165 mil 283, con un promedio diario de 640 deportaciones. Las nuevas cifras elevan el promedio diario a 650 deportados. ICE tambi\u00e9n explic\u00f3 que los pa\u00edses con mayor n\u00famero de deportados son: M\u00e9xico, con 132 mil 529; Guatemala, con 30 mil 807; El Salvador, con 19 mil 940; y Honduras, con 18 mil 445. El reporte del ICE tambi\u00e9n revel\u00f3 que a finales del mes de agosto fueron deportados 214 mil 264 inmigrantes indocumentados, de ellos, 126 mil 283 ten\u00eda antecedentes criminales (58.89%). El resto, 87 mil 981 (equivalente al 41.1%) no ten\u00eda antecedentes, dijo N\u00e9stor Yglesias, vocero de ICE. Fuente: Univisi\u00f3n<\/p>","protected":false},"author":13,"featured_media":2107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s de 2 millones de deportados en lo que va del 2015<\/title>\n<meta name=\"description\" content=\"La cifra total de deportados hasta el 31 de agosto es de 2 millones 488 mil 302, seg\u00fan datos de la Oficina de Inmigraci\u00f3n y Aduanas (ICE).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 2 millones de deportados en lo que va del 2015\" \/>\n<meta property=\"og:description\" content=\"La cifra total de deportados hasta el 31 de agosto es de 2 millones 488 mil 302, seg\u00fan datos de la Oficina de Inmigraci\u00f3n y Aduanas (ICE).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-11T21:55:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T02:59:36+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"M\u00e1s de 2 millones de deportados en lo que va del 2015\",\"datePublished\":\"2015-09-11T21:55:20+00:00\",\"dateModified\":\"2025-10-30T02:59:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/\"},\"wordCount\":217,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/\",\"name\":\"M\u00e1s de 2 millones de deportados en lo que va del 2015\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-09-11T21:55:20+00:00\",\"dateModified\":\"2025-10-30T02:59:36+00:00\",\"description\":\"La cifra total de deportados hasta el 31 de agosto es de 2 millones 488 mil 302, seg\u00fan datos de la Oficina de Inmigraci\u00f3n y Aduanas (ICE).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e1s de 2 millones de deportados en lo que va del 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 2 millones de deportados en lo que va del 2015","description":"La cifra total de deportados hasta el 31 de agosto es de 2 millones 488 mil 302, seg\u00fan datos de la Oficina de Inmigraci\u00f3n y Aduanas (ICE).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e1s de 2 millones de deportados en lo que va del 2015","og_description":"La cifra total de deportados hasta el 31 de agosto es de 2 millones 488 mil 302, seg\u00fan datos de la Oficina de Inmigraci\u00f3n y Aduanas (ICE).","og_url":"https:\/\/accesolatino.org\/en\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-09-11T21:55:20+00:00","article_modified_time":"2025-10-30T02:59:36+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"M\u00e1s de 2 millones de deportados en lo que va del 2015","datePublished":"2015-09-11T21:55:20+00:00","dateModified":"2025-10-30T02:59:36+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/"},"wordCount":217,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/","name":"M\u00e1s de 2 millones de deportados en lo que va del 2015","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-09-11T21:55:20+00:00","dateModified":"2025-10-30T02:59:36+00:00","description":"La cifra total de deportados hasta el 31 de agosto es de 2 millones 488 mil 302, seg\u00fan datos de la Oficina de Inmigraci\u00f3n y Aduanas (ICE).","breadcrumb":{"@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/mas-de-2-millones-de-deportados-en-lo-que-va-del-ano-fiscal-2015\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"M\u00e1s de 2 millones de deportados en lo que va del 2015"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12123"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12123\/revisions"}],"predecessor-version":[{"id":68112,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12123\/revisions\/68112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}