{"id":12086,"date":"2015-07-23T11:55:00","date_gmt":"2015-07-23T16:55:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=1733"},"modified":"2025-10-29T21:54:29","modified_gmt":"2025-10-30T03:54:29","slug":"hispanos-de-florida-positivos-en-su-situacion-financiera","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/","title":{"rendered":"Hispanos de Florida positivos de su situaci\u00f3n financiera"},"content":{"rendered":"<p><strong>Seg\u00fan una encuesta de la Florida Atlantic University Business and Economics Polling Initiative revela que la mayor\u00eda de los hispanos en la Florida dicen estar en mejor situaci\u00f3n financiera que hace un a\u00f1o<\/strong> y esperan que la buena racha contin\u00fae para ellos y sus negocios en el futuro.<\/p>\n<p>La mejor percepci\u00f3n de la situaci\u00f3n econ\u00f3mica en los hispanos se encuentra concentrada en el centro y sur del estado, mientras que la regi\u00f3n norte de la Florida es la que m\u00e1s resiente el aspecto econ\u00f3mico.<\/p>\n<p>La encuesta tambi\u00e9n encontr\u00f3 que los hispanos de origen mexicano o chicano perciben su econom\u00eda peor que los cubanos o los hispanos de otras nacionalidades.<\/p>\n<p><strong>El 65 por ciento de los hispanos en la Florida dicen que se encuentran en mejor situaci\u00f3n financiera que hace un a\u00f1o.<\/strong> En cuanto a las regiones los hispanos del centro del estado perciben su econom\u00eda mejor con respecto al a\u00f1o pasado en un 70 por ciento, comparado con el 65 por ciento del sur de la Florida y el 60.5 por ciento del norte del estado.<\/p>\n<p>El 69 por ciento de los encuestados hispanos dice que es un buen momento para comprar mobiliario importante para su hogar. En el centro del estado fueron el 71.4 por ciento de los encuestados los que contestaron afirmativamente en comparaci\u00f3n con el 69.4 por ciento del sur y el 64.7 por ciento del norte.<\/p>\n<p>Los hispanos de la Florida que ven de forma optimista su futuro econ\u00f3mico son el 74 por ciento, mientras que en la regi\u00f3n central fue de 80.1 por ciento, en el sur fueron el 74.4 por ciento y en el norte el 66.9 por ciento.<\/p>\n<p>La doctora M\u00f3nica Escaleras, directora de la encuestadora afirm\u00f3 que <strong>los hispanos en la Florida se sienten mejor con respecto a las finanzas personales y la econom\u00eda debido al gran impulso que han tenido las industrias del entretenimiento y restauranteras en el estado en los \u00faltimos a\u00f1os.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuente:<\/strong> <em>Newswise<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan una encuesta de la Florida Atlantic University Business and Economics Polling Initiative revela que la mayor\u00eda de los hispanos en la Florida dicen estar en mejor situaci\u00f3n financiera que hace un a\u00f1o y esperan que la buena racha contin\u00fae para ellos y sus negocios en el futuro. La mejor percepci\u00f3n de la situaci\u00f3n econ\u00f3mica en los hispanos se encuentra concentrada en el centro y sur del estado, mientras que la regi\u00f3n norte de la Florida es la que m\u00e1s resiente el aspecto econ\u00f3mico. La encuesta tambi\u00e9n encontr\u00f3 que los hispanos de origen mexicano o chicano perciben su econom\u00eda peor que los cubanos o los hispanos de otras nacionalidades. El 65 por ciento de los hispanos en la Florida dicen que se encuentran en mejor situaci\u00f3n financiera que hace un a\u00f1o. En cuanto a las regiones los hispanos del centro del estado perciben su econom\u00eda mejor con respecto al a\u00f1o pasado en un 70 por ciento, comparado con el 65 por ciento del sur de la Florida y el 60.5 por ciento del norte del estado. El 69 por ciento de los encuestados hispanos dice que es un buen momento para comprar mobiliario importante para su hogar. En el centro del estado fueron el 71.4 por ciento de los encuestados los que contestaron afirmativamente en comparaci\u00f3n con el 69.4 por ciento del sur y el 64.7 por ciento del norte. Los hispanos de la Florida que ven de forma optimista su futuro econ\u00f3mico son el 74 por ciento, mientras que en la regi\u00f3n central fue de 80.1 por ciento, en el sur fueron el 74.4 por ciento y en el norte el 66.9 por ciento. La doctora M\u00f3nica Escaleras, directora de la encuestadora afirm\u00f3 que los hispanos en la Florida se sienten mejor con respecto a las finanzas personales y la econom\u00eda debido al gran impulso que han tenido las industrias del entretenimiento y restauranteras en el estado en los \u00faltimos a\u00f1os. &nbsp; Fuente: Newswise<\/p>","protected":false},"author":13,"featured_media":1735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hispanos de Florida positivos de su situaci\u00f3n financiera<\/title>\n<meta name=\"description\" content=\"Una encuesta revela que la mayor\u00eda de los hispanos en la Florida dicen estar en mejor situaci\u00f3n financiera que hace un a\u00f1o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hispanos de Florida positivos de su situaci\u00f3n financiera\" \/>\n<meta property=\"og:description\" content=\"Una encuesta revela que la mayor\u00eda de los hispanos en la Florida dicen estar en mejor situaci\u00f3n financiera que hace un a\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-23T16:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T03:54:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Telefonos-de-ayuda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Hispanos de Florida positivos de su situaci\u00f3n financiera\",\"datePublished\":\"2015-07-23T16:55:00+00:00\",\"dateModified\":\"2025-10-30T03:54:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/\"},\"wordCount\":345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Telefonos-de-ayuda.jpg\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/\",\"name\":\"Hispanos de Florida positivos de su situaci\u00f3n financiera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Telefonos-de-ayuda.jpg\",\"datePublished\":\"2015-07-23T16:55:00+00:00\",\"dateModified\":\"2025-10-30T03:54:29+00:00\",\"description\":\"Una encuesta revela que la mayor\u00eda de los hispanos en la Florida dicen estar en mejor situaci\u00f3n financiera que hace un a\u00f1o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Telefonos-de-ayuda.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Telefonos-de-ayuda.jpg\",\"width\":\"1000\",\"height\":\"665\",\"caption\":\"migrantes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/hispanos-de-florida-positivos-en-su-situacion-financiera\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hispanos de Florida positivos de su situaci\u00f3n financiera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hispanos de Florida positivos de su situaci\u00f3n financiera","description":"Una encuesta revela que la mayor\u00eda de los hispanos en la Florida dicen estar en mejor situaci\u00f3n financiera que hace un a\u00f1o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"Hispanos de Florida positivos de su situaci\u00f3n financiera","og_description":"Una encuesta revela que la mayor\u00eda de los hispanos en la Florida dicen estar en mejor situaci\u00f3n financiera que hace un a\u00f1o.","og_url":"https:\/\/accesolatino.org\/en\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-07-23T16:55:00+00:00","article_modified_time":"2025-10-30T03:54:29+00:00","og_image":[{"width":1000,"height":665,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Telefonos-de-ayuda.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Hispanos de Florida positivos de su situaci\u00f3n financiera","datePublished":"2015-07-23T16:55:00+00:00","dateModified":"2025-10-30T03:54:29+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/"},"wordCount":345,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Telefonos-de-ayuda.jpg","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/","name":"Hispanos de Florida positivos de su situaci\u00f3n financiera","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Telefonos-de-ayuda.jpg","datePublished":"2015-07-23T16:55:00+00:00","dateModified":"2025-10-30T03:54:29+00:00","description":"Una encuesta revela que la mayor\u00eda de los hispanos en la Florida dicen estar en mejor situaci\u00f3n financiera que hace un a\u00f1o.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Telefonos-de-ayuda.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Telefonos-de-ayuda.jpg","width":"1000","height":"665","caption":"migrantes"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/hispanos-de-florida-positivos-en-su-situacion-financiera\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Hispanos de Florida positivos de su situaci\u00f3n financiera"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12086"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12086\/revisions"}],"predecessor-version":[{"id":68177,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12086\/revisions\/68177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/1735"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}