{"id":12078,"date":"2015-07-02T16:55:05","date_gmt":"2015-07-02T21:55:05","guid":{"rendered":"https:\/\/accesolatino.org\/?p=1542"},"modified":"2025-10-29T22:34:56","modified_gmt":"2025-10-30T04:34:56","slug":"estados-unidos-el-segundo-pais-que-mas-habla-espanol","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/","title":{"rendered":"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol"},"content":{"rendered":"<p>De acuerdo con un nuevo estudio publicado por el Instituto Cervantes, dedicado a promover la difusi\u00f3n y ense\u00f1anza del espa\u00f1ol, <strong>Estados Unidos ya es el segundo pa\u00eds con m\u00e1s hispanoparlantes. La Uni\u00f3n Americana solo se encuentra por debajo de M\u00e9xico.<\/strong><\/p>\n<p>El Instituto Cervantes apunta que <strong>Estados Unidos es el hogar de 41 millones de nativos del idioma espa\u00f1ol a los que hay que sumarle 11.6 millones de biling\u00fces.<\/strong> Los nuevos datos colocan a Estados Unidos por encima de pa\u00edses como Colombia (48 millones de hispanoparlantes) y Espa\u00f1a (46 millones de hispanoparlantes).<\/p>\n<p>Con 121 millones de personas que hablan espa\u00f1ol, M\u00e9xico sigue como el primer lugar de la lista.<\/p>\n<p>El Instituto Cervantes tom\u00f3 los datos del \u00faltimo censo que estima adem\u00e1s que<strong> para el a\u00f1o 2050 en Estados Unidos habr\u00e1 138 millones de personas que hablen espa\u00f1ol, convirti\u00e9ndose en el pa\u00eds que m\u00e1s habla espa\u00f1ol.<\/strong><\/p>\n<p>La mayor concentraci\u00f3n de hispanoparlantes en Estados Unidos est\u00e1 en los estados de Nuevo M\u00e9xico (47 por ciento de hispanoparlantes en el estado), California (38 por ciento), Texas (38 por ciento) y Arizona (30 por ciento). Un estado con una mayor\u00eda importante es Nueva York con el 18 por ciento de personas que hablan espa\u00f1ol. Un dato que salta a la vista por lo sorprendente es que m\u00e1s del 6 por ciento de los habitantes de Alaska hablan espa\u00f1ol. El estado con menos hispanoparlantes es Virginia Occidental con solo el 1.3 por ciento de sus habitantes.<\/p>\n<p>El informe estima que <strong>alrededor del mundo hay 559 millones de personas que hablan espa\u00f1ol, de los cuales 470 millones son nativos del idioma.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuente:<\/strong> <em>The Guardian<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>De acuerdo con un nuevo estudio publicado por el Instituto Cervantes, dedicado a promover la difusi\u00f3n y ense\u00f1anza del espa\u00f1ol, Estados Unidos ya es el segundo pa\u00eds con m\u00e1s hispanoparlantes. La Uni\u00f3n Americana solo se encuentra por debajo de M\u00e9xico. El Instituto Cervantes apunta que Estados Unidos es el hogar de 41 millones de nativos del idioma espa\u00f1ol a los que hay que sumarle 11.6 millones de biling\u00fces. Los nuevos datos colocan a Estados Unidos por encima de pa\u00edses como Colombia (48 millones de hispanoparlantes) y Espa\u00f1a (46 millones de hispanoparlantes). Con 121 millones de personas que hablan espa\u00f1ol, M\u00e9xico sigue como el primer lugar de la lista. El Instituto Cervantes tom\u00f3 los datos del \u00faltimo censo que estima adem\u00e1s que para el a\u00f1o 2050 en Estados Unidos habr\u00e1 138 millones de personas que hablen espa\u00f1ol, convirti\u00e9ndose en el pa\u00eds que m\u00e1s habla espa\u00f1ol. La mayor concentraci\u00f3n de hispanoparlantes en Estados Unidos est\u00e1 en los estados de Nuevo M\u00e9xico (47 por ciento de hispanoparlantes en el estado), California (38 por ciento), Texas (38 por ciento) y Arizona (30 por ciento). Un estado con una mayor\u00eda importante es Nueva York con el 18 por ciento de personas que hablan espa\u00f1ol. Un dato que salta a la vista por lo sorprendente es que m\u00e1s del 6 por ciento de los habitantes de Alaska hablan espa\u00f1ol. El estado con menos hispanoparlantes es Virginia Occidental con solo el 1.3 por ciento de sus habitantes. El informe estima que alrededor del mundo hay 559 millones de personas que hablan espa\u00f1ol, de los cuales 470 millones son nativos del idioma. &nbsp; Fuente: The Guardian<\/p>","protected":false},"author":13,"featured_media":1543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"De acuerdo con un nuevo estudio publicado por el Instituto Cervantes, Estados Unidos ya es el segundo pa\u00eds en el que m\u00e1s se habla espa\u00f1ol.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"De acuerdo con un nuevo estudio publicado por el Instituto Cervantes, Estados Unidos ya es el segundo pa\u00eds en el que m\u00e1s se habla espa\u00f1ol.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-02T21:55:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T04:34:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2016\/10\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1038\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol\",\"datePublished\":\"2015-07-02T21:55:05+00:00\",\"dateModified\":\"2025-10-30T04:34:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/\"},\"wordCount\":291,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/\",\"name\":\"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg\",\"datePublished\":\"2015-07-02T21:55:05+00:00\",\"dateModified\":\"2025-10-30T04:34:56+00:00\",\"description\":\"De acuerdo con un nuevo estudio publicado por el Instituto Cervantes, Estados Unidos ya es el segundo pa\u00eds en el que m\u00e1s se habla espa\u00f1ol.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg\",\"width\":\"1600\",\"height\":\"1038\",\"caption\":\"loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol","description":"De acuerdo con un nuevo estudio publicado por el Instituto Cervantes, Estados Unidos ya es el segundo pa\u00eds en el que m\u00e1s se habla espa\u00f1ol.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol","og_description":"De acuerdo con un nuevo estudio publicado por el Instituto Cervantes, Estados Unidos ya es el segundo pa\u00eds en el que m\u00e1s se habla espa\u00f1ol.","og_url":"https:\/\/accesolatino.org\/en\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-07-02T21:55:05+00:00","article_modified_time":"2025-10-30T04:34:56+00:00","og_image":[{"width":1600,"height":1038,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2016\/10\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol","datePublished":"2015-07-02T21:55:05+00:00","dateModified":"2025-10-30T04:34:56+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/"},"wordCount":291,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2016\/10\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/","name":"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2016\/10\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg","datePublished":"2015-07-02T21:55:05+00:00","dateModified":"2025-10-30T04:34:56+00:00","description":"De acuerdo con un nuevo estudio publicado por el Instituto Cervantes, Estados Unidos ya es el segundo pa\u00eds en el que m\u00e1s se habla espa\u00f1ol.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2016\/10\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2016\/10\/Loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card.jpg","width":"1600","height":"1038","caption":"loteria-de-visas-como-debes-rellenar-tu-solicitud-para-una-green-card"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/estados-unidos-el-segundo-pais-que-mas-habla-espanol\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Estados Unidos, el segundo pa\u00eds que m\u00e1s habla espa\u00f1ol"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12078"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12078\/revisions"}],"predecessor-version":[{"id":68223,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12078\/revisions\/68223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/1543"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}