{"id":12065,"date":"2015-07-07T11:55:22","date_gmt":"2015-07-07T16:55:22","guid":{"rendered":"https:\/\/accesolatino.org\/?p=1566"},"modified":"2025-10-29T22:36:42","modified_gmt":"2025-10-30T04:36:42","slug":"latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/","title":{"rendered":"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n"},"content":{"rendered":"<p>Seg\u00fan un informe de la ACT y Excelencia en la Educaci\u00f3n <strong>los estudiantes latinos son los que m\u00e1s se retrasan en sus cursos de preparaci\u00f3n para la universidad, en comparaci\u00f3n con estudiantes de otros grupos \u00e9tnicos<\/strong>, esto a pesar de que muchos estudiantes latinos quieren tener estudios superiores.<\/p>\n<p>El estudio revel\u00f3 que el 83 por ciento de los estudiantes latinos de High School en 2014 mostraron inter\u00e9s en llegar a la universidad, sin embargo por lo menos el 47 por ciento de los estudiantes latinos de la cifra antes citada no cumpli\u00f3 con ninguno de los cuatro requisitos de la ACT (Ingl\u00e9s, Matem\u00e1ticas, Ciencias y Lectura).<\/p>\n<p>El 31 por ciento del total de los graduados de High School de todos los grupos \u00e9tnicos tampoco cumpli\u00f3 con ninguno de los cuatro requisitos.<\/p>\n<p>Se calcula que a nivel nacional uno de cada cuatro estudiantes de escuela p\u00fablica es hispano y se espera que estas cifras aumenten en los pr\u00f3ximos a\u00f1os.<\/p>\n<p>El aumento en <strong>el n\u00famero de estudiantes latinos en las escuelas p\u00fablicas se debe a que las cifras han aumentado en casi un 80 por ciento entre 2010 y 2014, al pasar de 157 mil 579 a 281 mil 216.<\/strong><\/p>\n<p>Jim Larimore, presidente de ACT apunta que hay una creciente necesidad de proporcionar una educaci\u00f3n de calidad a los estudiantes.<\/p>\n<p>Sin embargo tambi\u00e9n se han observado avances, por ejemplo el porcentaje de estudiantes latinos que han cumplido los cuatro requisitos de ACT pasaron de un 11 a un 14 por ciento.<\/p>\n<p>Deborah Santiago,  directora de operaciones y vicepresidente de la pol\u00edtica para la Excelencia en la Educaci\u00f3n hizo votos por mejorar las condiciones de estudio para los latinos: <em>\u201cLos estudiantes latinos contin\u00faan avanzando, pero m\u00e1s se debe hacer (&#8230;.) Las escuelas deben proporcionar acceso a los estudiantes latinos a cursos rigurosos, implementar m\u00e1s servicios de apoyo al estudiante y hacer participar a los padres en las intervenciones tempranas\u201d.<\/em><\/p>\n<p><strong>Fuente:<\/strong> <em>La Opini\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan un informe de la ACT y Excelencia en la Educaci\u00f3n los estudiantes latinos son los que m\u00e1s se retrasan en sus cursos de preparaci\u00f3n para la universidad, en comparaci\u00f3n con estudiantes de otros grupos \u00e9tnicos, esto a pesar de que muchos estudiantes latinos quieren tener estudios superiores. El estudio revel\u00f3 que el 83 por ciento de los estudiantes latinos de High School en 2014 mostraron inter\u00e9s en llegar a la universidad, sin embargo por lo menos el 47 por ciento de los estudiantes latinos de la cifra antes citada no cumpli\u00f3 con ninguno de los cuatro requisitos de la ACT (Ingl\u00e9s, Matem\u00e1ticas, Ciencias y Lectura). El 31 por ciento del total de los graduados de High School de todos los grupos \u00e9tnicos tampoco cumpli\u00f3 con ninguno de los cuatro requisitos. Se calcula que a nivel nacional uno de cada cuatro estudiantes de escuela p\u00fablica es hispano y se espera que estas cifras aumenten en los pr\u00f3ximos a\u00f1os. El aumento en el n\u00famero de estudiantes latinos en las escuelas p\u00fablicas se debe a que las cifras han aumentado en casi un 80 por ciento entre 2010 y 2014, al pasar de 157 mil 579 a 281 mil 216. Jim Larimore, presidente de ACT apunta que hay una creciente necesidad de proporcionar una educaci\u00f3n de calidad a los estudiantes. Sin embargo tambi\u00e9n se han observado avances, por ejemplo el porcentaje de estudiantes latinos que han cumplido los cuatro requisitos de ACT pasaron de un 11 a un 14 por ciento. Deborah Santiago, directora de operaciones y vicepresidente de la pol\u00edtica para la Excelencia en la Educaci\u00f3n hizo votos por mejorar las condiciones de estudio para los latinos: \u201cLos estudiantes latinos contin\u00faan avanzando, pero m\u00e1s se debe hacer (&#8230;.) Las escuelas deben proporcionar acceso a los estudiantes latinos a cursos rigurosos, implementar m\u00e1s servicios de apoyo al estudiante y hacer participar a los padres en las intervenciones tempranas\u201d. Fuente: La Opini\u00f3n<\/p>","protected":false},"author":13,"featured_media":1567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Los estudiantes latinos son los que m\u00e1s se retrasan en sus cursos de preparaci\u00f3n para la universidad, en comparaci\u00f3n con estudiantes de otros grupos \u00e9tnicos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Los estudiantes latinos son los que m\u00e1s se retrasan en sus cursos de preparaci\u00f3n para la universidad, en comparaci\u00f3n con estudiantes de otros grupos \u00e9tnicos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-07T16:55:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T04:36:42+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n\",\"datePublished\":\"2015-07-07T16:55:22+00:00\",\"dateModified\":\"2025-10-30T04:36:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/\"},\"wordCount\":338,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/\",\"name\":\"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-07-07T16:55:22+00:00\",\"dateModified\":\"2025-10-30T04:36:42+00:00\",\"description\":\"Los estudiantes latinos son los que m\u00e1s se retrasan en sus cursos de preparaci\u00f3n para la universidad, en comparaci\u00f3n con estudiantes de otros grupos \u00e9tnicos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n","description":"Los estudiantes latinos son los que m\u00e1s se retrasan en sus cursos de preparaci\u00f3n para la universidad, en comparaci\u00f3n con estudiantes de otros grupos \u00e9tnicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n","og_description":"Los estudiantes latinos son los que m\u00e1s se retrasan en sus cursos de preparaci\u00f3n para la universidad, en comparaci\u00f3n con estudiantes de otros grupos \u00e9tnicos","og_url":"https:\/\/accesolatino.org\/en\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-07-07T16:55:22+00:00","article_modified_time":"2025-10-30T04:36:42+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n","datePublished":"2015-07-07T16:55:22+00:00","dateModified":"2025-10-30T04:36:42+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/"},"wordCount":338,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/","name":"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-07-07T16:55:22+00:00","dateModified":"2025-10-30T04:36:42+00:00","description":"Los estudiantes latinos son los que m\u00e1s se retrasan en sus cursos de preparaci\u00f3n para la universidad, en comparaci\u00f3n con estudiantes de otros grupos \u00e9tnicos","breadcrumb":{"@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/latinos-los-que-mas-se-retrasan-en-cursos-de-preparacion\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Latinos los que m\u00e1s se retrasan en cursos de preparaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12065"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12065\/revisions"}],"predecessor-version":[{"id":68230,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12065\/revisions\/68230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}