{"id":12058,"date":"2015-06-24T11:55:24","date_gmt":"2015-06-24T16:55:24","guid":{"rendered":"https:\/\/accesolatino.org\/?p=1489"},"modified":"2025-10-29T23:07:12","modified_gmt":"2025-10-30T05:07:12","slug":"suspension-de-dapa-deja-a-menores-en-un-limbo","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/","title":{"rendered":"Suspensi\u00f3n de DAPA deja a menores en un limbo"},"content":{"rendered":"<p><strong>La demora de los alivios migratorios por la suspensi\u00f3n de DAPA ha provocado la incertidumbre para los menores de edad cuyos padres han sido deportados.<\/strong><\/p>\n<p>Se calcula que por la detenci\u00f3n o deportaci\u00f3n de uno de los padres <strong>m\u00e1s de 5 mil ni\u00f1os han terminado en hogares temporales, esto seg\u00fan un informe que data de 2011.<\/strong><\/p>\n<p>Activistas y diversos expertos en materia de inmigraci\u00f3n han pedido al Quinto Circuito de Apelaciones con sede en Nueva Orleans que se est\u00e1 encargando de estudiar estos casos que tome en cuenta la dif\u00edcil situaci\u00f3n en la que viven los padres indocumentados que podr\u00edan beneficiarse del programa de acci\u00f3n diferida para los adultos, es decir DAPA, que se encuentra frenado por una demanda interpuesta por 26 estados de la Uni\u00f3n Americana.<\/p>\n<p>Se calcula que de los 6.3 millones de ni\u00f1os que tienen por lo menos un padre indocumentado elegible para DAPA, el 83 por ciento de estos, es decir 5.5 millones nacieron en los Estados Unidos.<\/p>\n<p>En caso de que DAPA sea aprobado aliviar\u00eda la situaci\u00f3n de los padres indocumentados ya que podr\u00edan contar con un permiso de trabajo, lo que resolver\u00eda sus problemas de vivienda y alimentaci\u00f3n.<\/p>\n<p><strong>Actualmente las autoridades migratorias reciben solo solicitudes para el programa DACA que le dar\u00eda estatus legal a aquellos que llegaron en la infancia a Estados Unidos, una versi\u00f3n extendida de DACA junto con DAPA se encuentran suspendidas y en litigio en el Tribunal del Quinto Circuito de Apelaciones.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuente:<\/strong> <em>La Opini\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>La demora de los alivios migratorios por la suspensi\u00f3n de DAPA ha provocado la incertidumbre para los menores de edad cuyos padres han sido deportados. Se calcula que por la detenci\u00f3n o deportaci\u00f3n de uno de los padres m\u00e1s de 5 mil ni\u00f1os han terminado en hogares temporales, esto seg\u00fan un informe que data de 2011. Activistas y diversos expertos en materia de inmigraci\u00f3n han pedido al Quinto Circuito de Apelaciones con sede en Nueva Orleans que se est\u00e1 encargando de estudiar estos casos que tome en cuenta la dif\u00edcil situaci\u00f3n en la que viven los padres indocumentados que podr\u00edan beneficiarse del programa de acci\u00f3n diferida para los adultos, es decir DAPA, que se encuentra frenado por una demanda interpuesta por 26 estados de la Uni\u00f3n Americana. Se calcula que de los 6.3 millones de ni\u00f1os que tienen por lo menos un padre indocumentado elegible para DAPA, el 83 por ciento de estos, es decir 5.5 millones nacieron en los Estados Unidos. En caso de que DAPA sea aprobado aliviar\u00eda la situaci\u00f3n de los padres indocumentados ya que podr\u00edan contar con un permiso de trabajo, lo que resolver\u00eda sus problemas de vivienda y alimentaci\u00f3n. Actualmente las autoridades migratorias reciben solo solicitudes para el programa DACA que le dar\u00eda estatus legal a aquellos que llegaron en la infancia a Estados Unidos, una versi\u00f3n extendida de DACA junto con DAPA se encuentran suspendidas y en litigio en el Tribunal del Quinto Circuito de Apelaciones. &nbsp; Fuente: La Opini\u00f3n<\/p>","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12058","post","type-post","status-publish","format-standard","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suspensi\u00f3n de DAPA deja a menores en un limbo<\/title>\n<meta name=\"description\" content=\"La demora de los alivios migratorios por la suspensi\u00f3n de DAPA ha provocado la incertidumbre para los menores de edad cuyos padres han sido deportados.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suspensi\u00f3n de DAPA deja a menores en un limbo\" \/>\n<meta property=\"og:description\" content=\"La demora de los alivios migratorios por la suspensi\u00f3n de DAPA ha provocado la incertidumbre para los menores de edad cuyos padres han sido deportados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-24T16:55:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T05:07:12+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/suspension-de-dapa-deja-a-menores-en-un-limbo\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/suspension-de-dapa-deja-a-menores-en-un-limbo\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Suspensi\u00f3n de DAPA deja a menores en un limbo\",\"datePublished\":\"2015-06-24T16:55:24+00:00\",\"dateModified\":\"2025-10-30T05:07:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/suspension-de-dapa-deja-a-menores-en-un-limbo\\\/temas-de-interes\\\/\"},\"wordCount\":271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/suspension-de-dapa-deja-a-menores-en-un-limbo\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/suspension-de-dapa-deja-a-menores-en-un-limbo\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/suspension-de-dapa-deja-a-menores-en-un-limbo\\\/temas-de-interes\\\/\",\"name\":\"Suspensi\u00f3n de DAPA deja a menores en un limbo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"datePublished\":\"2015-06-24T16:55:24+00:00\",\"dateModified\":\"2025-10-30T05:07:12+00:00\",\"description\":\"La demora de los alivios migratorios por la suspensi\u00f3n de DAPA ha provocado la incertidumbre para los menores de edad cuyos padres han sido deportados.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/suspension-de-dapa-deja-a-menores-en-un-limbo\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/suspension-de-dapa-deja-a-menores-en-un-limbo\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/suspension-de-dapa-deja-a-menores-en-un-limbo\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Suspensi\u00f3n de DAPA deja a menores en un limbo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suspensi\u00f3n de DAPA deja a menores en un limbo","description":"La demora de los alivios migratorios por la suspensi\u00f3n de DAPA ha provocado la incertidumbre para los menores de edad cuyos padres han sido deportados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"Suspensi\u00f3n de DAPA deja a menores en un limbo","og_description":"La demora de los alivios migratorios por la suspensi\u00f3n de DAPA ha provocado la incertidumbre para los menores de edad cuyos padres han sido deportados.","og_url":"https:\/\/accesolatino.org\/en\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-06-24T16:55:24+00:00","article_modified_time":"2025-10-30T05:07:12+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Suspensi\u00f3n de DAPA deja a menores en un limbo","datePublished":"2015-06-24T16:55:24+00:00","dateModified":"2025-10-30T05:07:12+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/"},"wordCount":271,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/","name":"Suspensi\u00f3n de DAPA deja a menores en un limbo","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"datePublished":"2015-06-24T16:55:24+00:00","dateModified":"2025-10-30T05:07:12+00:00","description":"La demora de los alivios migratorios por la suspensi\u00f3n de DAPA ha provocado la incertidumbre para los menores de edad cuyos padres han sido deportados.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/suspension-de-dapa-deja-a-menores-en-un-limbo\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Suspensi\u00f3n de DAPA deja a menores en un limbo"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12058"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12058\/revisions"}],"predecessor-version":[{"id":68287,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12058\/revisions\/68287"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}