{"id":12052,"date":"2015-06-20T11:55:30","date_gmt":"2015-06-20T16:55:30","guid":{"rendered":"https:\/\/accesolatino.org\/?p=1469"},"modified":"2025-10-29T23:06:09","modified_gmt":"2025-10-30T05:06:09","slug":"el-primer-abogado-indocumentado-sera-ciudadano","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/","title":{"rendered":"El primer abogado indocumentado ser\u00e1 ciudadano"},"content":{"rendered":"<p>Sergio C. Garc\u00eda se convirti\u00f3 en el primer abogado indocumentado autorizado para ejercer el derecho a pesar de no tener documentos para probar su estad\u00eda legal en los Estados Unidos y ahora <strong>se encuentra en el camino para recibir un estatus legal en el pa\u00eds.<\/strong><\/p>\n<p>El abogado hace un recuento de lo que tuvo que pasar para convertirse en un abogado con licencia a pesar de ser indocumentado. Garc\u00eda asegura que a\u00fan guarda la copia del pago inicial necesario para iniciar el camino para convertirse en un abogado con licencia, un proceso que dur\u00f3 m\u00e1s de dos d\u00e9cadas.<\/p>\n<p>Una de las cosas con las que tambi\u00e9n tuvo que lidiar fue con <strong>la barrera del idioma que lo llev\u00f3 a ser alguien t\u00edmido debido a la inseguridad que ten\u00eda por no hablar el ingl\u00e9s de manera fluida y tener un acento muy marcado, a lo que se sumaba el choque cultural por venir de una cultura y de un pa\u00eds completamente diferente.<\/strong><\/p>\n<p>Garc\u00eda apunt\u00f3 que por no tener papeles lleg\u00f3 a perder varias oportunidades de trabajo, a pesar de ser una persona debidamente preparada y con estudios universitarios.<\/p>\n<p>El abogado tambi\u00e9n explic\u00f3 que para terminar sus estudios sobrevivi\u00f3 juntando botes de aluminio y nueces para vender, ya que era una persona de escasos recursos y quer\u00eda tener estudios universitarios.<\/p>\n<p>Despu\u00e9s de muchos esfuerzos lleg\u00f3 a la escuela de leyes, y termin\u00f3 su carrera en cinco a\u00f1os para que dos d\u00e9cadas m\u00e1s tarde pudiera obtener una licencia para ejercer su profesi\u00f3n en el pa\u00eds a pesar de no tener documentos y ahora se encuentra en camino para su legalizaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuente:<\/strong> <em>La Opini\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Sergio C. Garc\u00eda se convirti\u00f3 en el primer abogado indocumentado autorizado para ejercer el derecho a pesar de no tener documentos para probar su estad\u00eda legal en los Estados Unidos y ahora se encuentra en el camino para recibir un estatus legal en el pa\u00eds. El abogado hace un recuento de lo que tuvo que pasar para convertirse en un abogado con licencia a pesar de ser indocumentado. Garc\u00eda asegura que a\u00fan guarda la copia del pago inicial necesario para iniciar el camino para convertirse en un abogado con licencia, un proceso que dur\u00f3 m\u00e1s de dos d\u00e9cadas. Una de las cosas con las que tambi\u00e9n tuvo que lidiar fue con la barrera del idioma que lo llev\u00f3 a ser alguien t\u00edmido debido a la inseguridad que ten\u00eda por no hablar el ingl\u00e9s de manera fluida y tener un acento muy marcado, a lo que se sumaba el choque cultural por venir de una cultura y de un pa\u00eds completamente diferente. Garc\u00eda apunt\u00f3 que por no tener papeles lleg\u00f3 a perder varias oportunidades de trabajo, a pesar de ser una persona debidamente preparada y con estudios universitarios. El abogado tambi\u00e9n explic\u00f3 que para terminar sus estudios sobrevivi\u00f3 juntando botes de aluminio y nueces para vender, ya que era una persona de escasos recursos y quer\u00eda tener estudios universitarios. Despu\u00e9s de muchos esfuerzos lleg\u00f3 a la escuela de leyes, y termin\u00f3 su carrera en cinco a\u00f1os para que dos d\u00e9cadas m\u00e1s tarde pudiera obtener una licencia para ejercer su profesi\u00f3n en el pa\u00eds a pesar de no tener documentos y ahora se encuentra en camino para su legalizaci\u00f3n. &nbsp; Fuente: La Opini\u00f3n<\/p>","protected":false},"author":13,"featured_media":1470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-12052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El primer abogado indocumentado ser\u00e1 ciudadano<\/title>\n<meta name=\"description\" content=\"Sergio C. Garc\u00eda el primer abogado indocumentado autorizado para ejercer el derecho se encuentra en el camino para recibir un estatus legal en el pa\u00eds.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El primer abogado indocumentado ser\u00e1 ciudadano\" \/>\n<meta property=\"og:description\" content=\"Sergio C. Garc\u00eda el primer abogado indocumentado autorizado para ejercer el derecho se encuentra en el camino para recibir un estatus legal en el pa\u00eds.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-20T16:55:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T05:06:09+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"El primer abogado indocumentado ser\u00e1 ciudadano\",\"datePublished\":\"2015-06-20T16:55:30+00:00\",\"dateModified\":\"2025-10-30T05:06:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/\"},\"wordCount\":300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/\",\"name\":\"El primer abogado indocumentado ser\u00e1 ciudadano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-06-20T16:55:30+00:00\",\"dateModified\":\"2025-10-30T05:06:09+00:00\",\"description\":\"Sergio C. Garc\u00eda el primer abogado indocumentado autorizado para ejercer el derecho se encuentra en el camino para recibir un estatus legal en el pa\u00eds.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-primer-abogado-indocumentado-sera-ciudadano\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El primer abogado indocumentado ser\u00e1 ciudadano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El primer abogado indocumentado ser\u00e1 ciudadano","description":"Sergio C. Garc\u00eda el primer abogado indocumentado autorizado para ejercer el derecho se encuentra en el camino para recibir un estatus legal en el pa\u00eds.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"El primer abogado indocumentado ser\u00e1 ciudadano","og_description":"Sergio C. Garc\u00eda el primer abogado indocumentado autorizado para ejercer el derecho se encuentra en el camino para recibir un estatus legal en el pa\u00eds.","og_url":"https:\/\/accesolatino.org\/en\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-06-20T16:55:30+00:00","article_modified_time":"2025-10-30T05:06:09+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"El primer abogado indocumentado ser\u00e1 ciudadano","datePublished":"2015-06-20T16:55:30+00:00","dateModified":"2025-10-30T05:06:09+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/"},"wordCount":300,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/","name":"El primer abogado indocumentado ser\u00e1 ciudadano","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-06-20T16:55:30+00:00","dateModified":"2025-10-30T05:06:09+00:00","description":"Sergio C. Garc\u00eda el primer abogado indocumentado autorizado para ejercer el derecho se encuentra en el camino para recibir un estatus legal en el pa\u00eds.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/el-primer-abogado-indocumentado-sera-ciudadano\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"El primer abogado indocumentado ser\u00e1 ciudadano"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=12052"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12052\/revisions"}],"predecessor-version":[{"id":68282,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/12052\/revisions\/68282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=12052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=12052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=12052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}